{"id":6327,"date":"2024-03-22T05:39:29","date_gmt":"2024-03-22T05:39:29","guid":{"rendered":"https:\/\/uat-demo.com\/mitk\/?page_id=6327"},"modified":"2026-04-06T07:27:47","modified_gmt":"2026-04-06T07:27:47","slug":"councils-committees","status":"publish","type":"page","link":"https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/","title":{"rendered":"Councils &amp; Committees"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6327\" class=\"elementor elementor-6327\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f288235 e-con-full e-flex e-con e-parent\" data-id=\"f288235\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;background_background&quot;:&quot;gradient&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-245abf3 elementor-widget elementor-widget-heading\" data-id=\"245abf3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Councils & Committees<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3425e3 elementor-widget elementor-widget-text-editor\" data-id=\"e3425e3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Supporting student growth and campus governance through active councils, committees, and leadership initiatives.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ea6386a e-flex e-con-boxed e-con e-parent\" data-id=\"ea6386a\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13fea86 elementor-widget elementor-widget-elementskit-simple-tab\" data-id=\"13fea86\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_hash_change&quot;:&quot;1&quot;}\" data-widget_type=\"elementskit-simple-tab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <div class=\"elementkit-tab-wraper   elementskit-fitcontent-tab \">\n            <ul class=\"nav nav-tabs elementkit-tab-nav \">\n                                    <li class=\"elementkit-nav-item elementor-repeater-item-4b47708\">\n                        <a class=\"elementkit-nav-link  active show top-pos\" id=\"content-4b477086a97bd05bf974-tab\" data-ekit-handler-id=\"governing-council\" data-ekit-toggle=\"tab\" data-target=\"#content-4b477086a97bd05bf974\" href=\"#Content-4b477086a97bd05bf974\"\n                            data-ekit-toggle-trigger=\"click\"\n                            aria-describedby=\"Content-4b477086a97bd05bf974\">\n                            <span class=\" elementskit-tab-icon\"><\/span>                            <span class=\"elementskit-tab-title\"> Governing Council<\/span>\n                        <\/a>\n                    <\/li>\n                                        <li class=\"elementkit-nav-item elementor-repeater-item-48a7c4f\">\n                        <a class=\"elementkit-nav-link  top-pos\" id=\"content-48a7c4f6a97bd05bf974-tab\" data-ekit-handler-id=\"academic-council\" data-ekit-toggle=\"tab\" data-target=\"#content-48a7c4f6a97bd05bf974\" href=\"#Content-48a7c4f6a97bd05bf974\"\n                            data-ekit-toggle-trigger=\"click\"\n                            aria-describedby=\"Content-48a7c4f6a97bd05bf974\">\n                            <span class=\" elementskit-tab-icon\"><\/span>                            <span class=\"elementskit-tab-title\"> Academic Council<\/span>\n                        <\/a>\n                    <\/li>\n                                        <li class=\"elementkit-nav-item elementor-repeater-item-9c71503\">\n                        <a class=\"elementkit-nav-link  top-pos\" id=\"content-9c715036a97bd05bf974-tab\" data-ekit-handler-id=\"committees\" data-ekit-toggle=\"tab\" data-target=\"#content-9c715036a97bd05bf974\" href=\"#Content-9c715036a97bd05bf974\"\n                            data-ekit-toggle-trigger=\"click\"\n                            aria-describedby=\"Content-9c715036a97bd05bf974\">\n                            <span class=\" elementskit-tab-icon\"><\/span>                            <span class=\"elementskit-tab-title\"> Committees<\/span>\n                        <\/a>\n                    <\/li>\n                                <\/ul>\n\n            <div class=\"tab-content elementkit-tab-content\">\n                                    <div class=\"tab-pane elementkit-tab-pane elementor-repeater-item-4b47708  active show\" id=\"content-4b477086a97bd05bf974\" role=\"tabpanel\"\n                         aria-labelledby=\"content-4b477086a97bd05bf974-tab\">\n                        <div class=\"animated fadeIn\">\n                            <p>\t\t<div data-elementor-type=\"container\" data-elementor-id=\"6341\" class=\"elementor elementor-6341\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c6c08a e-grid e-con-boxed e-con e-parent\" data-id=\"6c6c08a\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;grid&quot;,&quot;grid_columns_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;3&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;content_width&quot;:&quot;boxed&quot;,&quot;grid_outline&quot;:&quot;yes&quot;,&quot;grid_columns_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_columns_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;grid_rows_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_auto_flow&quot;:&quot;row&quot;,&quot;grid_auto_flow_tablet&quot;:&quot;row&quot;,&quot;grid_auto_flow_mobile&quot;:&quot;row&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3614c2a e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"3614c2a\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-981ad58 e-con-full e-flex e-con e-child\" data-id=\"981ad58\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ee4853 elementor-widget elementor-widget-image\" data-id=\"9ee4853\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855.png\" class=\"attachment-full size-full wp-image-6343\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c8a1e6 e-con-full e-flex e-con e-child\" data-id=\"9c8a1e6\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f575992 elementor-widget elementor-widget-heading\" data-id=\"f575992\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Sri. Siddartha J Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0926ec1 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0926ec1\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/www.mitkundapura.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Educationist<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Trustee, Chairman<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-94613ef e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"94613ef\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a9e7f76 e-con-full e-flex e-con e-child\" data-id=\"a9e7f76\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fb77c4 elementor-widget elementor-widget-image\" data-id=\"1fb77c4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50835.png\" class=\"attachment-full size-full wp-image-19610\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-475b4fe e-con-full e-flex e-con e-child\" data-id=\"475b4fe\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19f0728 elementor-widget elementor-widget-heading\" data-id=\"19f0728\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Ramakrishna Hegde<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42d0e23 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"42d0e23\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Principal\/Member Secretary<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member Secretary<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-643d181 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"643d181\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-20e79d9 e-con-full e-flex e-con e-child\" data-id=\"20e79d9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4875421 elementor-widget elementor-widget-image\" data-id=\"4875421\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Dr.-S-N-Bhat.png\" class=\"attachment-full size-full wp-image-22675\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f671ea e-con-full e-flex e-con e-child\" data-id=\"3f671ea\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b36987 elementor-widget elementor-widget-heading\" data-id=\"4b36987\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. S N Bhat<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2af85eb elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2af85eb\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Director Academics IMJ Institutions<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member Secretary<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dad54fa e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"dad54fa\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d8b1322 e-con-full e-flex e-con e-child\" data-id=\"d8b1322\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e1e50f elementor-widget elementor-widget-image\" data-id=\"7e1e50f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-3.png\" class=\"attachment-full size-full wp-image-6363\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd2e103 e-con-full e-flex e-con e-child\" data-id=\"bd2e103\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8102f08 elementor-widget elementor-widget-heading\" data-id=\"8102f08\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Sri. Ram Rathan J Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f635319 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f635319\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Industrialist<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65e90e8 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"65e90e8\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e5d9035 e-con-full e-flex e-con e-child\" data-id=\"e5d9035\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab639c5 elementor-widget elementor-widget-image\" data-id=\"ab639c5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c53dac e-con-full e-flex e-con e-child\" data-id=\"2c53dac\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fed0d5 elementor-widget elementor-widget-heading\" data-id=\"2fed0d5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Anisha Rai<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bbccd3 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9bbccd3\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c60578 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"8c60578\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-37ceedc e-con-full e-flex e-con e-child\" data-id=\"37ceedc\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14e0e55 elementor-widget elementor-widget-image\" data-id=\"14e0e55\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f8a6ef e-con-full e-flex e-con e-child\" data-id=\"5f8a6ef\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-914817b elementor-widget elementor-widget-heading\" data-id=\"914817b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Jayakar Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98e490a elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"98e490a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Social Activist<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07be550 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"07be550\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-eff5c67 e-con-full e-flex e-con e-child\" data-id=\"eff5c67\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4304415 elementor-widget elementor-widget-image\" data-id=\"4304415\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Mr.-Shivananda-Kamath.png\" class=\"attachment-full size-full wp-image-22679\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9772fa7 e-con-full e-flex e-con e-child\" data-id=\"9772fa7\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e898cb elementor-widget elementor-widget-heading\" data-id=\"8e898cb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Shivananda Kamath<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ffdba0 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1ffdba0\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Director at Wafersys Technologies UDUPI<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74b4db2 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"74b4db2\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cbfd3d7 e-con-full e-flex e-con e-child\" data-id=\"cbfd3d7\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a519cc3 elementor-widget elementor-widget-image\" data-id=\"a519cc3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"97\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50755.png\" class=\"attachment-full size-full wp-image-17122\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7091063 e-con-full e-flex e-con e-child\" data-id=\"7091063\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-301ac1c elementor-widget elementor-widget-heading\" data-id=\"301ac1c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Kiran Nayak<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da62313 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"da62313\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Managing Partner of Bharati software, India<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f05e7af e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"f05e7af\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b45476c e-con-full e-flex e-con e-child\" data-id=\"b45476c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-214298c elementor-widget elementor-widget-image\" data-id=\"214298c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Mrs.-Sumangala-Thunga.png\" class=\"attachment-full size-full wp-image-22683\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bfa6345 e-con-full e-flex e-con e-child\" data-id=\"bfa6345\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-758533d elementor-widget elementor-widget-heading\" data-id=\"758533d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Sumangala Thunga<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-396867e elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"396867e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Director and Delivery Head at Prolake Technologies Pvt Lt<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member pro lake<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-506f038 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"506f038\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9ca77d0 e-con-full e-flex e-con e-child\" data-id=\"9ca77d0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-366b0df elementor-widget elementor-widget-image\" data-id=\"366b0df\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"97\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50754.png\" class=\"attachment-full size-full wp-image-17123\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d684f2 e-con-full e-flex e-con e-child\" data-id=\"3d684f2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbfbd7f elementor-widget elementor-widget-heading\" data-id=\"dbfbd7f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Niranjan U C<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25016d2 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"25016d2\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Academician<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f32769 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"6f32769\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bc016c1 e-con-full e-flex e-con e-child\" data-id=\"bc016c1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-658ed76 elementor-widget elementor-widget-image\" data-id=\"658ed76\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"97\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50758.png\" class=\"attachment-full size-full wp-image-17119\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84ca64b e-con-full e-flex e-con e-child\" data-id=\"84ca64b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3424cda elementor-widget elementor-widget-heading\" data-id=\"3424cda\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Praveen Kumar Kalbhavi<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68b20fb elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"68b20fb\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Managing Director &#038; CEO Novigo Solutions Pvt Lt<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-db8000b e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"db8000b\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5a3b742 e-con-full e-flex e-con e-child\" data-id=\"5a3b742\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7726ae elementor-widget elementor-widget-image\" data-id=\"f7726ae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-1.png\" class=\"attachment-full size-full wp-image-6358\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8598685 e-con-full e-flex e-con e-child\" data-id=\"8598685\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-564d724 elementor-widget elementor-widget-heading\" data-id=\"564d724\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Smt. Vidya J Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dea4df elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2dea4df\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Industrialist<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc9cac1 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"cc9cac1\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5c623e6 e-con-full e-flex e-con e-child\" data-id=\"5c623e6\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f3ab01 elementor-widget elementor-widget-image\" data-id=\"9f3ab01\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"97\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-14.png\" class=\"attachment-full size-full wp-image-17125\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ae2beb e-con-full e-flex e-con e-child\" data-id=\"9ae2beb\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b639f96 elementor-widget elementor-widget-heading\" data-id=\"b639f96\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Vinod John<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7112fd elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c7112fd\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : VP Mirafra Technologies<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee64278 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"ee64278\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-33e7505 e-con-full e-flex e-con e-child\" data-id=\"33e7505\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c504cc3 elementor-widget elementor-widget-image\" data-id=\"c504cc3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Mrs.-Amruthmala.png\" class=\"attachment-full size-full wp-image-22690\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e646fe2 e-con-full e-flex e-con e-child\" data-id=\"e646fe2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c4d525 elementor-widget elementor-widget-heading\" data-id=\"0c4d525\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Amruthmala<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f49058 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2f49058\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : DEAN, Training Placement &#038; Industry Relation<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7e9eff e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"b7e9eff\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f7393a1 e-con-full e-flex e-con e-child\" data-id=\"f7393a1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d664d32 elementor-widget elementor-widget-image\" data-id=\"d664d32\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Mrs.-Akshatha-Naik.png\" class=\"attachment-full size-full wp-image-22692\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-edcabd9 e-con-full e-flex e-con e-child\" data-id=\"edcabd9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e86104 elementor-widget elementor-widget-heading\" data-id=\"1e86104\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Akshatha Naik<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f81edf elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0f81edf\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Dean Student welfare MITK<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a96f6ee e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"a96f6ee\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6e0d6f9 e-con-full e-flex e-con e-child\" data-id=\"6e0d6f9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c99c161 elementor-widget elementor-widget-image\" data-id=\"c99c161\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"97\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50757.png\" class=\"attachment-full size-full wp-image-17120\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d40df0e e-con-full e-flex e-con e-child\" data-id=\"d40df0e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de10398 elementor-widget elementor-widget-heading\" data-id=\"de10398\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Rathnakar Bhat<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19de562 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"19de562\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Industrialist<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96edf2b e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"96edf2b\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c7867cb e-con-full e-flex e-con e-child\" data-id=\"c7867cb\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4172d0 elementor-widget elementor-widget-image\" data-id=\"d4172d0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"97\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50756.png\" class=\"attachment-full size-full wp-image-17121\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b0e8fd4 e-con-full e-flex e-con e-child\" data-id=\"b0e8fd4\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-053754c elementor-widget elementor-widget-heading\" data-id=\"053754c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Ranjitha Prabhu<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9d690d elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d9d690d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Entrepreneur<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b336fc0 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"b336fc0\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2304c10 e-con-full e-flex e-con e-child\" data-id=\"2304c10\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3de51d5 elementor-widget elementor-widget-image\" data-id=\"3de51d5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f79535d e-con-full e-flex e-con e-child\" data-id=\"f79535d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ff406a elementor-widget elementor-widget-heading\" data-id=\"9ff406a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Shivanand<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8af1f1c elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8af1f1c\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Entrepreneur<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ad11cb e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"1ad11cb\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d24aa3f e-con-full e-flex e-con e-child\" data-id=\"d24aa3f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccf3680 elementor-widget elementor-widget-image\" data-id=\"ccf3680\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"97\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50753.png\" class=\"attachment-full size-full wp-image-17124\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d18024 e-con-full e-flex e-con e-child\" data-id=\"3d18024\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4ba0a4 elementor-widget elementor-widget-heading\" data-id=\"d4ba0a4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Sumanth Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-152359f elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"152359f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Entrepreneur<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ce5190 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"7ce5190\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-81b2fb5 e-con-full e-flex e-con e-child\" data-id=\"81b2fb5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eeb412a elementor-widget elementor-widget-image\" data-id=\"eeb412a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0747021 e-con-full e-flex e-con e-child\" data-id=\"0747021\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-738ad7f elementor-widget elementor-widget-heading\" data-id=\"738ad7f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Captain Ganesh Karnik<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f418fd0 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f418fd0\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Educationist<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8892429 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"8892429\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-abf1465 e-con-full e-flex e-con e-child\" data-id=\"abf1465\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34d0622 elementor-widget elementor-widget-image\" data-id=\"34d0622\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-966dd01 e-con-full e-flex e-con e-child\" data-id=\"966dd01\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-959d046 elementor-widget elementor-widget-heading\" data-id=\"959d046\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Harish B.<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7fdc18 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c7fdc18\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Entrepreneur<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b5b1ca e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"8b5b1ca\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c06e38d e-con-full e-flex e-con e-child\" data-id=\"c06e38d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0b30bf elementor-widget elementor-widget-image\" data-id=\"b0b30bf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-77745c0 e-con-full e-flex e-con e-child\" data-id=\"77745c0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6219634 elementor-widget elementor-widget-heading\" data-id=\"6219634\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Anand C Kunder<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dfae31 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9dfae31\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Industrialist<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aba846f e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"aba846f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0327a07 e-con-full e-flex e-con e-child\" data-id=\"0327a07\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fafdd4a elementor-widget elementor-widget-image\" data-id=\"fafdd4a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fa4a1e0 e-con-full e-flex e-con e-child\" data-id=\"fa4a1e0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61aa08c elementor-widget elementor-widget-heading\" data-id=\"61aa08c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Mehal B. Rai<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d17856 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2d17856\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Entrepreneur<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36b3d57 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"36b3d57\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9d08915 e-con-full e-flex e-con e-child\" data-id=\"9d08915\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d4e004 elementor-widget elementor-widget-image\" data-id=\"8d4e004\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18d11c1 e-con-full e-flex e-con e-child\" data-id=\"18d11c1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-361c9c8 elementor-widget elementor-widget-heading\" data-id=\"361c9c8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Shreerama Reddy<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e45e079 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e45e079\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Principal CBIT Kolar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : VTU Nominee<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d572564 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"d572564\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-900bcd1 e-con-full e-flex e-con e-child\" data-id=\"900bcd1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2442dd elementor-widget elementor-widget-image\" data-id=\"a2442dd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4270364 e-con-full e-flex e-con e-child\" data-id=\"4270364\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6692c41 elementor-widget elementor-widget-heading\" data-id=\"6692c41\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prof. Thimmappa D S.<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf3f1bd elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"cf3f1bd\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Faculty, MITK<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>                        <\/div>\n                    <\/div>\n                                    <div class=\"tab-pane elementkit-tab-pane elementor-repeater-item-48a7c4f \" id=\"content-48a7c4f6a97bd05bf974\" role=\"tabpanel\"\n                         aria-labelledby=\"content-48a7c4f6a97bd05bf974-tab\">\n                        <div class=\"animated fadeIn\">\n                            <p>\t\t<div data-elementor-type=\"container\" data-elementor-id=\"6374\" class=\"elementor elementor-6374\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06cdc54 e-grid e-con-boxed e-con e-parent\" data-id=\"06cdc54\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;grid&quot;,&quot;grid_columns_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;3&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;content_width&quot;:&quot;boxed&quot;,&quot;grid_outline&quot;:&quot;yes&quot;,&quot;grid_columns_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_columns_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;grid_rows_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_auto_flow&quot;:&quot;row&quot;,&quot;grid_auto_flow_tablet&quot;:&quot;row&quot;,&quot;grid_auto_flow_mobile&quot;:&quot;row&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e1c4453 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"e1c4453\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-64d5386 e-con-full e-flex e-con e-child\" data-id=\"64d5386\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc0340f elementor-widget elementor-widget-image\" data-id=\"fc0340f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855.png\" class=\"attachment-full size-full wp-image-6343\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60cb4df e-con-full e-flex e-con e-child\" data-id=\"60cb4df\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d78f34 elementor-widget elementor-widget-heading\" data-id=\"3d78f34\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Sri. Siddartha J Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6457de7 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6457de7\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession : Educationist<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Chairman<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb0e87a e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"cb0e87a\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-18a64c7 e-con-full e-flex e-con e-child\" data-id=\"18a64c7\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd66dc3 elementor-widget elementor-widget-image\" data-id=\"cd66dc3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50835.png\" class=\"attachment-full size-full wp-image-19610\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4970753 e-con-full e-flex e-con e-child\" data-id=\"4970753\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2da0135 elementor-widget elementor-widget-heading\" data-id=\"2da0135\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Ramakrishna Hegde<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b77a3d elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8b77a3d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Principal, Chairman of Academic Council<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9fd6b0d e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"9fd6b0d\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7c7b4ad e-con-full e-flex e-con e-child\" data-id=\"7c7b4ad\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a1407c8 elementor-widget elementor-widget-image\" data-id=\"a1407c8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c1f31a e-con-full e-flex e-con e-child\" data-id=\"0c1f31a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17bbc17 elementor-widget elementor-widget-heading\" data-id=\"17bbc17\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Prathibha M Patel<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-577ab69 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"577ab69\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : DEAN, Academics &#038; Quality Assurance<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-374ac6b e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"374ac6b\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5a01efc e-con-full e-flex e-con e-child\" data-id=\"5a01efc\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f137fe elementor-widget elementor-widget-image\" data-id=\"9f137fe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-7.png\" class=\"attachment-full size-full wp-image-6387\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d30253 e-con-full e-flex e-con e-child\" data-id=\"5d30253\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b443dd3 elementor-widget elementor-widget-heading\" data-id=\"b443dd3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Amruthmala<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d52634f elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d52634f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : DEAN, Training Placement &#038; Industry Relation<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5815fa2 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"5815fa2\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fdd56d1 e-con-full e-flex e-con e-child\" data-id=\"fdd56d1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37cefd2 elementor-widget elementor-widget-image\" data-id=\"37cefd2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ad1d76 e-con-full e-flex e-con e-child\" data-id=\"7ad1d76\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66ef53a elementor-widget elementor-widget-heading\" data-id=\"66ef53a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Pradeep Kumar Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7273fef elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7273fef\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Administrative officer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b745a6 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"8b745a6\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d7ea37c e-con-full e-flex e-con e-child\" data-id=\"d7ea37c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e52507 elementor-widget elementor-widget-image\" data-id=\"7e52507\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50837.png\" class=\"attachment-full size-full wp-image-19616\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56d49bf e-con-full e-flex e-con e-child\" data-id=\"56d49bf\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55cce8f elementor-widget elementor-widget-heading\" data-id=\"55cce8f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Akshatha Naik<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b16b176 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b16b176\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Dean, Student Welfare<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32fa26e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"32fa26e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-47e255b e-con-full e-flex e-con e-child\" data-id=\"47e255b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91dc4bc elementor-widget elementor-widget-image\" data-id=\"91dc4bc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50868-1.png\" class=\"attachment-full size-full wp-image-20095\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b35142c e-con-full e-flex e-con e-child\" data-id=\"b35142c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dab55ff elementor-widget elementor-widget-heading\" data-id=\"dab55ff\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Indra Vijay Singh<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a669cd9 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a669cd9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : HOD (CSE(AIML), AIML) &#038; Associate Professor <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9bdad05 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"9bdad05\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-67a1db6 e-con-full e-flex e-con e-child\" data-id=\"67a1db6\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fedbe60 elementor-widget elementor-widget-image\" data-id=\"fedbe60\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50876.png\" class=\"attachment-full size-full wp-image-20104\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f5b816d e-con-full e-flex e-con e-child\" data-id=\"f5b816d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4b557b elementor-widget elementor-widget-heading\" data-id=\"d4b557b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Deepak Shetty M<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edf74b9 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"edf74b9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Associate Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-00dcf11 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"00dcf11\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-74278ba e-con-full e-flex e-con e-child\" data-id=\"74278ba\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-720f300 elementor-widget elementor-widget-image\" data-id=\"720f300\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/mr.manjunath.png\" class=\"attachment-full size-full wp-image-22699\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f76fa1e e-con-full e-flex e-con e-child\" data-id=\"f76fa1e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba63967 elementor-widget elementor-widget-heading\" data-id=\"ba63967\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Manjunath R Lamani<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1885b2a elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1885b2a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Associate Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b0eee03 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"b0eee03\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0fe2218 e-con-full e-flex e-con e-child\" data-id=\"0fe2218\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c18a98f elementor-widget elementor-widget-image\" data-id=\"c18a98f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50932.png\" class=\"attachment-full size-full wp-image-24008\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bceb1ae e-con-full e-flex e-con e-child\" data-id=\"bceb1ae\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43bbbc7 elementor-widget elementor-widget-heading\" data-id=\"43bbbc7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Sam Abraham\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9af5e2c elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9af5e2c\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Associate Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e560f1e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"e560f1e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-722e083 e-con-full e-flex e-con e-child\" data-id=\"722e083\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fabffcd elementor-widget elementor-widget-image\" data-id=\"fabffcd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50840-1.png\" class=\"attachment-full size-full wp-image-20101\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c876128 e-con-full e-flex e-con e-child\" data-id=\"c876128\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51eedac elementor-widget elementor-widget-heading\" data-id=\"51eedac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Varuna Kumara<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6498b7f elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6498b7f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Associate Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31236b0 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"31236b0\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c734c4c e-con-full e-flex e-con e-child\" data-id=\"c734c4c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cdafe47 elementor-widget elementor-widget-image\" data-id=\"cdafe47\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"97\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50760.png\" class=\"attachment-full size-full wp-image-17823\" alt=\"FACULTY IMAGE\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d0f306 e-con-full e-flex e-con e-child\" data-id=\"3d0f306\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad25beb elementor-widget elementor-widget-heading\" data-id=\"ad25beb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Suchitra<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3bc4ce elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e3bc4ce\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : HOD (MBA) &#038; Associate Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>                        <\/div>\n                    <\/div>\n                                    <div class=\"tab-pane elementkit-tab-pane elementor-repeater-item-9c71503 \" id=\"content-9c715036a97bd05bf974\" role=\"tabpanel\"\n                         aria-labelledby=\"content-9c715036a97bd05bf974-tab\">\n                        <div class=\"animated fadeIn\">\n                            <p>\t\t<div data-elementor-type=\"container\" data-elementor-id=\"6395\" class=\"elementor elementor-6395\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95f17ca e-flex e-con-boxed e-con e-parent\" data-id=\"95f17ca\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-667b50f elementor-widget elementor-widget-heading\" data-id=\"667b50f\" data-element_type=\"widget\" id=\"icc\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Internal Complaint Committee (ICC)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-85b4476 e-flex e-con-boxed e-con e-parent\" data-id=\"85b4476\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bcf6ca elementor-widget elementor-widget-text-editor\" data-id=\"5bcf6ca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<strong>Preamble:<\/strong> \n<br>This committee is constituted under the provisions of section 4 of Sexual Harassment of women at work place prevention, prohibition and redressal Act, 2013 and All India Council for Technical Regulations, 2016 for the benefit of women employees and students and some male students and students of third gender. The committee will look into complaints received from women staff members and take necessary actions to ensure discrimination free, harassment-free campus. <br><br><strong>Objectives:<\/strong> <br>1. To develop a policy against sexual harassment of women at the institute. <br>2. To ensure implementation of policy in letter and spent through proper reporting of complaints and then follow up procedures. <br>3. To uphold the commitment of the institute to provide an environment free of gender discrimination and sexual harassment.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64795cd e-grid e-con-boxed e-con e-parent\" data-id=\"64795cd\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;grid&quot;,&quot;grid_columns_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;3&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;content_width&quot;:&quot;boxed&quot;,&quot;grid_outline&quot;:&quot;yes&quot;,&quot;grid_columns_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_columns_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;grid_rows_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_auto_flow&quot;:&quot;row&quot;,&quot;grid_auto_flow_tablet&quot;:&quot;row&quot;,&quot;grid_auto_flow_mobile&quot;:&quot;row&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0a78e42 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"0a78e42\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-accd537 e-con-full e-flex e-con e-child\" data-id=\"accd537\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aad3621 elementor-widget elementor-widget-image\" data-id=\"aad3621\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50848-1.png\" class=\"attachment-full size-full wp-image-20110\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-df4f0bb e-con-full e-flex e-con e-child\" data-id=\"df4f0bb\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f62a590 elementor-widget elementor-widget-heading\" data-id=\"f62a590\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Ramakrishna Hegde<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a66300 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2a66300\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M18.3001 3.75082H14.7545V2.83545C14.7542 2.50287 14.6219 2.18402 14.3867 1.94885C14.1516 1.71369 13.8327 1.58141 13.5001 1.58105H9.57864C9.24604 1.58141 8.92717 1.71368 8.69198 1.94884C8.45678 2.18401 8.32447 2.50286 8.32407 2.83545V3.75082H4.81048C4.51504 3.75113 4.23179 3.86862 4.02286 4.07751C3.81394 4.28641 3.6964 4.56964 3.69605 4.86509V8.20756C3.69591 8.2733 3.71777 8.33721 3.75815 8.38909C3.79852 8.44098 3.8551 8.47786 3.91887 8.49387L4.2515 8.57808V14.3071C4.25181 14.602 4.36911 14.8848 4.57766 15.0933C4.78621 15.3019 5.06898 15.4192 5.36391 15.4195H17.7467C18.0416 15.4192 18.3244 15.3019 18.533 15.0933C18.7416 14.8848 18.8589 14.602 18.8593 14.3071V8.57724L19.1917 8.49303C19.2555 8.47702 19.3121 8.44013 19.3525 8.38825C19.3928 8.33636 19.4147 8.27246 19.4146 8.20672V4.86576C19.4144 4.5702 19.2969 4.28679 19.088 4.07775C18.879 3.86871 18.5957 3.75113 18.3001 3.75082ZM8.91354 2.83545C8.91377 2.65914 8.98392 2.49012 9.1086 2.36546C9.23329 2.24081 9.40233 2.1707 9.57864 2.17053H13.5001C13.6764 2.1707 13.8455 2.24082 13.9701 2.36548C14.0948 2.49013 14.1649 2.65916 14.1651 2.83545V3.75082H8.91354V2.83545ZM4.28552 4.86576C4.28552 4.72648 4.34081 4.5929 4.43925 4.49437C4.53768 4.39584 4.67121 4.34042 4.81048 4.34029H18.301C18.4401 4.34042 18.5735 4.39575 18.672 4.49413C18.7704 4.59252 18.8258 4.72593 18.8259 4.86509V7.97817L18.497 8.06154H18.493L12.5796 9.56014V9.36242C12.5794 9.17478 12.5048 8.99485 12.3722 8.86207C12.2396 8.72929 12.0598 8.65449 11.8722 8.65404H11.2068C11.0189 8.65422 10.8389 8.72891 10.7061 8.86172C10.5732 8.99453 10.4986 9.1746 10.4984 9.36242V9.55054L4.61815 8.06238L4.28552 7.97817V4.86576ZM11.0879 9.92915V9.36242C11.0879 9.3309 11.1004 9.30068 11.1227 9.27839C11.145 9.2561 11.1752 9.24356 11.2068 9.24351H11.8722C11.9037 9.24356 11.9339 9.2561 11.9562 9.27839C11.9785 9.30068 11.991 9.3309 11.9911 9.36242V10.8255C11.991 10.857 11.9785 10.8872 11.9562 10.9095C11.9339 10.9318 11.9037 10.9443 11.8722 10.9444H11.2068C11.1752 10.9443 11.145 10.9318 11.1227 10.9095C11.1004 10.8872 11.0879 10.857 11.0879 10.8255V9.92915ZM17.7467 14.8302H5.36391C5.22527 14.83 5.09236 14.7749 4.99433 14.6768C4.8963 14.5788 4.84115 14.4459 4.84097 14.3072V8.7268L10.2905 10.106L10.4984 10.1587V10.8255C10.4983 10.8455 10.5004 10.8654 10.5044 10.8849C10.5191 11.0614 10.5993 11.2259 10.7293 11.346C10.8594 11.4662 11.0297 11.5332 11.2068 11.5339H11.8722C12.0492 11.5332 12.2196 11.4662 12.3496 11.346C12.4796 11.2259 12.5599 11.0614 12.5745 10.8849C12.5782 10.8653 12.5799 10.8454 12.5796 10.8255V10.1676L17.839 8.83476L18.2696 8.72562V14.3071C18.2695 14.4457 18.2143 14.5786 18.1163 14.6767C18.0182 14.7747 17.8853 14.83 17.7467 14.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Principal, MITK<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Chairman<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d76e663 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"d76e663\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-db8928f e-con-full e-flex e-con e-child\" data-id=\"db8928f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e1f50c elementor-widget elementor-widget-image\" data-id=\"6e1f50c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50845.png\" class=\"attachment-full size-full wp-image-20011\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e00cf3 e-con-full e-flex e-con e-child\" data-id=\"2e00cf3\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53ca2e2 elementor-widget elementor-widget-heading\" data-id=\"53ca2e2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Suchitra D. Poojari<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-955b1e7 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"955b1e7\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M18.3001 3.75082H14.7545V2.83545C14.7542 2.50287 14.6219 2.18402 14.3867 1.94885C14.1516 1.71369 13.8327 1.58141 13.5001 1.58105H9.57864C9.24604 1.58141 8.92717 1.71368 8.69198 1.94884C8.45678 2.18401 8.32447 2.50286 8.32407 2.83545V3.75082H4.81048C4.51504 3.75113 4.23179 3.86862 4.02286 4.07751C3.81394 4.28641 3.6964 4.56964 3.69605 4.86509V8.20756C3.69591 8.2733 3.71777 8.33721 3.75815 8.38909C3.79852 8.44098 3.8551 8.47786 3.91887 8.49387L4.2515 8.57808V14.3071C4.25181 14.602 4.36911 14.8848 4.57766 15.0933C4.78621 15.3019 5.06898 15.4192 5.36391 15.4195H17.7467C18.0416 15.4192 18.3244 15.3019 18.533 15.0933C18.7416 14.8848 18.8589 14.602 18.8593 14.3071V8.57724L19.1917 8.49303C19.2555 8.47702 19.3121 8.44013 19.3525 8.38825C19.3928 8.33636 19.4147 8.27246 19.4146 8.20672V4.86576C19.4144 4.5702 19.2969 4.28679 19.088 4.07775C18.879 3.86871 18.5957 3.75113 18.3001 3.75082ZM8.91354 2.83545C8.91377 2.65914 8.98392 2.49012 9.1086 2.36546C9.23329 2.24081 9.40233 2.1707 9.57864 2.17053H13.5001C13.6764 2.1707 13.8455 2.24082 13.9701 2.36548C14.0948 2.49013 14.1649 2.65916 14.1651 2.83545V3.75082H8.91354V2.83545ZM4.28552 4.86576C4.28552 4.72648 4.34081 4.5929 4.43925 4.49437C4.53768 4.39584 4.67121 4.34042 4.81048 4.34029H18.301C18.4401 4.34042 18.5735 4.39575 18.672 4.49413C18.7704 4.59252 18.8258 4.72593 18.8259 4.86509V7.97817L18.497 8.06154H18.493L12.5796 9.56014V9.36242C12.5794 9.17478 12.5048 8.99485 12.3722 8.86207C12.2396 8.72929 12.0598 8.65449 11.8722 8.65404H11.2068C11.0189 8.65422 10.8389 8.72891 10.7061 8.86172C10.5732 8.99453 10.4986 9.1746 10.4984 9.36242V9.55054L4.61815 8.06238L4.28552 7.97817V4.86576ZM11.0879 9.92915V9.36242C11.0879 9.3309 11.1004 9.30068 11.1227 9.27839C11.145 9.2561 11.1752 9.24356 11.2068 9.24351H11.8722C11.9037 9.24356 11.9339 9.2561 11.9562 9.27839C11.9785 9.30068 11.991 9.3309 11.9911 9.36242V10.8255C11.991 10.857 11.9785 10.8872 11.9562 10.9095C11.9339 10.9318 11.9037 10.9443 11.8722 10.9444H11.2068C11.1752 10.9443 11.145 10.9318 11.1227 10.9095C11.1004 10.8872 11.0879 10.857 11.0879 10.8255V9.92915ZM17.7467 14.8302H5.36391C5.22527 14.83 5.09236 14.7749 4.99433 14.6768C4.8963 14.5788 4.84115 14.4459 4.84097 14.3072V8.7268L10.2905 10.106L10.4984 10.1587V10.8255C10.4983 10.8455 10.5004 10.8654 10.5044 10.8849C10.5191 11.0614 10.5993 11.2259 10.7293 11.346C10.8594 11.4662 11.0297 11.5332 11.2068 11.5339H11.8722C12.0492 11.5332 12.2196 11.4662 12.3496 11.346C12.4796 11.2259 12.5599 11.0614 12.5745 10.8849C12.5782 10.8653 12.5799 10.8454 12.5796 10.8255V10.1676L17.839 8.83476L18.2696 8.72562V14.3071C18.2695 14.4457 18.2143 14.5786 18.1163 14.6767C18.0182 14.7747 17.8853 14.83 17.7467 14.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD-MBA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Co-Ordinator<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-229be02 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"229be02\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-49b92b9 e-con-full e-flex e-con e-child\" data-id=\"49b92b9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84cd3bd elementor-widget elementor-widget-image\" data-id=\"84cd3bd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-356419f e-con-full e-flex e-con e-child\" data-id=\"356419f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f71eae8 elementor-widget elementor-widget-heading\" data-id=\"f71eae8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Sookshma Adiga<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06c3a78 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"06c3a78\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M18.3001 3.75082H14.7545V2.83545C14.7542 2.50287 14.6219 2.18402 14.3867 1.94885C14.1516 1.71369 13.8327 1.58141 13.5001 1.58105H9.57864C9.24604 1.58141 8.92717 1.71368 8.69198 1.94884C8.45678 2.18401 8.32447 2.50286 8.32407 2.83545V3.75082H4.81048C4.51504 3.75113 4.23179 3.86862 4.02286 4.07751C3.81394 4.28641 3.6964 4.56964 3.69605 4.86509V8.20756C3.69591 8.2733 3.71777 8.33721 3.75815 8.38909C3.79852 8.44098 3.8551 8.47786 3.91887 8.49387L4.2515 8.57808V14.3071C4.25181 14.602 4.36911 14.8848 4.57766 15.0933C4.78621 15.3019 5.06898 15.4192 5.36391 15.4195H17.7467C18.0416 15.4192 18.3244 15.3019 18.533 15.0933C18.7416 14.8848 18.8589 14.602 18.8593 14.3071V8.57724L19.1917 8.49303C19.2555 8.47702 19.3121 8.44013 19.3525 8.38825C19.3928 8.33636 19.4147 8.27246 19.4146 8.20672V4.86576C19.4144 4.5702 19.2969 4.28679 19.088 4.07775C18.879 3.86871 18.5957 3.75113 18.3001 3.75082ZM8.91354 2.83545C8.91377 2.65914 8.98392 2.49012 9.1086 2.36546C9.23329 2.24081 9.40233 2.1707 9.57864 2.17053H13.5001C13.6764 2.1707 13.8455 2.24082 13.9701 2.36548C14.0948 2.49013 14.1649 2.65916 14.1651 2.83545V3.75082H8.91354V2.83545ZM4.28552 4.86576C4.28552 4.72648 4.34081 4.5929 4.43925 4.49437C4.53768 4.39584 4.67121 4.34042 4.81048 4.34029H18.301C18.4401 4.34042 18.5735 4.39575 18.672 4.49413C18.7704 4.59252 18.8258 4.72593 18.8259 4.86509V7.97817L18.497 8.06154H18.493L12.5796 9.56014V9.36242C12.5794 9.17478 12.5048 8.99485 12.3722 8.86207C12.2396 8.72929 12.0598 8.65449 11.8722 8.65404H11.2068C11.0189 8.65422 10.8389 8.72891 10.7061 8.86172C10.5732 8.99453 10.4986 9.1746 10.4984 9.36242V9.55054L4.61815 8.06238L4.28552 7.97817V4.86576ZM11.0879 9.92915V9.36242C11.0879 9.3309 11.1004 9.30068 11.1227 9.27839C11.145 9.2561 11.1752 9.24356 11.2068 9.24351H11.8722C11.9037 9.24356 11.9339 9.2561 11.9562 9.27839C11.9785 9.30068 11.991 9.3309 11.9911 9.36242V10.8255C11.991 10.857 11.9785 10.8872 11.9562 10.9095C11.9339 10.9318 11.9037 10.9443 11.8722 10.9444H11.2068C11.1752 10.9443 11.145 10.9318 11.1227 10.9095C11.1004 10.8872 11.0879 10.857 11.0879 10.8255V9.92915ZM17.7467 14.8302H5.36391C5.22527 14.83 5.09236 14.7749 4.99433 14.6768C4.8963 14.5788 4.84115 14.4459 4.84097 14.3072V8.7268L10.2905 10.106L10.4984 10.1587V10.8255C10.4983 10.8455 10.5004 10.8654 10.5044 10.8849C10.5191 11.0614 10.5993 11.2259 10.7293 11.346C10.8594 11.4662 11.0297 11.5332 11.2068 11.5339H11.8722C12.0492 11.5332 12.2196 11.4662 12.3496 11.346C12.4796 11.2259 12.5599 11.0614 12.5745 10.8849C12.5782 10.8653 12.5799 10.8454 12.5796 10.8255V10.1676L17.839 8.83476L18.2696 8.72562V14.3071C18.2695 14.4457 18.2143 14.5786 18.1163 14.6767C18.0182 14.7747 17.8853 14.83 17.7467 14.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student Welfare Coordinator<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member (Teaching)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c67ebc e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"9c67ebc\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-292926f e-con-full e-flex e-con e-child\" data-id=\"292926f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90379c4 elementor-widget elementor-widget-image\" data-id=\"90379c4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-8.png\" class=\"attachment-full size-full wp-image-6405\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d2eae6 e-con-full e-flex e-con e-child\" data-id=\"6d2eae6\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e6c4b9a elementor-widget elementor-widget-heading\" data-id=\"e6c4b9a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Akshatha Naik<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6a5c6f elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f6a5c6f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Dean Student Welfare<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ffd545e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"ffd545e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1d42a09 e-con-full e-flex e-con e-child\" data-id=\"1d42a09\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1667c4 elementor-widget elementor-widget-image\" data-id=\"c1667c4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c85e58 e-con-full e-flex e-con e-child\" data-id=\"1c85e58\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90a3b89 elementor-widget elementor-widget-heading\" data-id=\"90a3b89\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Jayram B Gowda<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-670fbfd elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"670fbfd\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Circle Inspector of Police<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d2b25a e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"3d2b25a\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-36156a4 e-con-full e-flex e-con e-child\" data-id=\"36156a4\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49e5aa8 elementor-widget elementor-widget-image\" data-id=\"49e5aa8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-9.png\" class=\"attachment-full size-full wp-image-6413\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-786bae0 e-con-full e-flex e-con e-child\" data-id=\"786bae0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-642bcca elementor-widget elementor-widget-heading\" data-id=\"642bcca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Sookshma Adiga<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da5c738 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"da5c738\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Assistant Professor <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0992f0 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"a0992f0\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-104f47a e-con-full e-flex e-con e-child\" data-id=\"104f47a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58dbf1d elementor-widget elementor-widget-image\" data-id=\"58dbf1d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c0dfba e-con-full e-flex e-con e-child\" data-id=\"9c0dfba\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-893db29 elementor-widget elementor-widget-heading\" data-id=\"893db29\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Nikhila<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f35e4d elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7f35e4d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Assistant Professor <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d93834 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"6d93834\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7a2cea0 e-con-full e-flex e-con e-child\" data-id=\"7a2cea0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10a6b00 elementor-widget elementor-widget-image\" data-id=\"10a6b00\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-854979d e-con-full e-flex e-con e-child\" data-id=\"854979d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-601fe9e elementor-widget elementor-widget-heading\" data-id=\"601fe9e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Asha<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e57f820 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e57f820\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Assistant Professor <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0584d1e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"0584d1e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-012978c e-con-full e-flex e-con e-child\" data-id=\"012978c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f09dade elementor-widget elementor-widget-image\" data-id=\"f09dade\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-7.png\" class=\"attachment-full size-full wp-image-6387\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42ab636 e-con-full e-flex e-con e-child\" data-id=\"42ab636\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed31d2b elementor-widget elementor-widget-heading\" data-id=\"ed31d2b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Amruthmala<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b27ba0b elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b27ba0b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Assistant Professor <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0be5983 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"0be5983\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fe1a495 e-con-full e-flex e-con e-child\" data-id=\"fe1a495\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55f1ff4 elementor-widget elementor-widget-image\" data-id=\"55f1ff4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50846.png\" class=\"attachment-full size-full wp-image-20013\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b3ab6c3 e-con-full e-flex e-con e-child\" data-id=\"b3ab6c3\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad768a9 elementor-widget elementor-widget-heading\" data-id=\"ad768a9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. T. Nandhini<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ccfe58 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6ccfe58\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD-MCA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member (Teaching)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-efaf6ce e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"efaf6ce\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e0aeaae e-con-full e-flex e-con e-child\" data-id=\"e0aeaae\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c264959 elementor-widget elementor-widget-image\" data-id=\"c264959\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/mr.manjunath.png\" class=\"attachment-full size-full wp-image-22699\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5969a6f e-con-full e-flex e-con e-child\" data-id=\"5969a6f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5efa298 elementor-widget elementor-widget-heading\" data-id=\"5efa298\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Manjunath R Lamani<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d969c8 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0d969c8\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD-CSE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member (Teaching)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd3c774 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"bd3c774\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9d0d938 e-con-full e-flex e-con e-child\" data-id=\"9d0d938\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b84b57 elementor-widget elementor-widget-image\" data-id=\"9b84b57\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b3f6016 e-con-full e-flex e-con e-child\" data-id=\"b3f6016\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83cb475 elementor-widget elementor-widget-heading\" data-id=\"83cb475\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Farana<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec4275b elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ec4275b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8cba115 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"8cba115\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-227a20c e-con-full e-flex e-con e-child\" data-id=\"227a20c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca267ac elementor-widget elementor-widget-image\" data-id=\"ca267ac\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1adaebe e-con-full e-flex e-con e-child\" data-id=\"1adaebe\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a07068e elementor-widget elementor-widget-heading\" data-id=\"a07068e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Meghana V<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0555597 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0555597\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9e1cf4 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"e9e1cf4\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9f59067 e-con-full e-flex e-con e-child\" data-id=\"9f59067\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7dd0a81 elementor-widget elementor-widget-image\" data-id=\"7dd0a81\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c27e984 e-con-full e-flex e-con e-child\" data-id=\"c27e984\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60abcdb elementor-widget elementor-widget-heading\" data-id=\"60abcdb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Fathima Tahasin<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c597b1 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2c597b1\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-693d05d e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"693d05d\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f3adce6 e-con-full e-flex e-con e-child\" data-id=\"f3adce6\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b210585 elementor-widget elementor-widget-image\" data-id=\"b210585\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-1000006298.png\" class=\"attachment-full size-full wp-image-25732\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cad3db1 e-con-full e-flex e-con e-child\" data-id=\"cad3db1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70b0b21 elementor-widget elementor-widget-heading\" data-id=\"70b0b21\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Shivanandaswamy Mahapurush<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b5831f elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7b5831f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assoc. Prof., ECE <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member (Teaching)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4911f77 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"4911f77\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-252f9fc e-con-full e-flex e-con e-child\" data-id=\"252f9fc\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01fc70d elementor-widget elementor-widget-image\" data-id=\"01fc70d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/11\/Group-1000006297.png\" class=\"attachment-full size-full wp-image-25729\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-572a80e e-con-full e-flex e-con e-child\" data-id=\"572a80e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5760880 elementor-widget elementor-widget-heading\" data-id=\"5760880\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Lakshmi<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ed3421 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0ed3421\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HoD Incharge ISE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member (Teaching)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d78697 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"2d78697\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a76b77b e-con-full e-flex e-con e-child\" data-id=\"a76b77b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-748eadf elementor-widget elementor-widget-image\" data-id=\"748eadf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50932.png\" class=\"attachment-full size-full wp-image-24008\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed28b27 e-con-full e-flex e-con e-child\" data-id=\"ed28b27\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f3c7a8d elementor-widget elementor-widget-heading\" data-id=\"f3c7a8d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Sam Abhram<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-131c221 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"131c221\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : HOD-DSE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b0d6c62 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"b0d6c62\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6daa04d e-con-full e-flex e-con e-child\" data-id=\"6daa04d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e95d506 elementor-widget elementor-widget-image\" data-id=\"e95d506\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50842-2.png\" class=\"attachment-full size-full wp-image-20009\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d557f2a e-con-full e-flex e-con e-child\" data-id=\"d557f2a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3eca240 elementor-widget elementor-widget-heading\" data-id=\"3eca240\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. J. Prakash<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb7982a elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bb7982a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : HOD-ISE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2a1f62b e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"2a1f62b\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6b69f51 e-con-full e-flex e-con e-child\" data-id=\"6b69f51\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf6a511 elementor-widget elementor-widget-image\" data-id=\"cf6a511\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50847.png\" class=\"attachment-full size-full wp-image-20015\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ad92fd3 e-con-full e-flex e-con e-child\" data-id=\"ad92fd3\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4235b4a elementor-widget elementor-widget-heading\" data-id=\"4235b4a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Nikhila Pai<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8a3221 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a8a3221\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: IQAC Coordinator<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member (Teaching)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1becc7f e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"1becc7f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-037d52b e-con-full e-flex e-con e-child\" data-id=\"037d52b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0abb882 elementor-widget elementor-widget-image\" data-id=\"0abb882\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-443bec9 e-con-full e-flex e-con e-child\" data-id=\"443bec9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4001661 elementor-widget elementor-widget-heading\" data-id=\"4001661\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Swathi <\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d073c6e elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d073c6e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Manager HR<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member (Non-teaching)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16d2caf e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"16d2caf\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f98c3c5 e-con-full e-flex e-con e-child\" data-id=\"f98c3c5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b2a0b2 elementor-widget elementor-widget-image\" data-id=\"7b2a0b2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd701af e-con-full e-flex e-con e-child\" data-id=\"fd701af\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8689460 elementor-widget elementor-widget-heading\" data-id=\"8689460\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Kripa Bhat<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9d9402 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d9d9402\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Director (CWC)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member from NGO<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-80c990e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"80c990e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ec445e8 e-con-full e-flex e-con e-child\" data-id=\"ec445e8\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c4615e elementor-widget elementor-widget-image\" data-id=\"9c4615e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50844.png\" class=\"attachment-full size-full wp-image-20017\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07007ce e-con-full e-flex e-con e-child\" data-id=\"07007ce\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-860ce23 elementor-widget elementor-widget-heading\" data-id=\"860ce23\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Roopashree Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e8517d elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6e8517d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Faculty-BSH<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aed714f e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"aed714f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0f36700 e-con-full e-flex e-con e-child\" data-id=\"0f36700\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb535cd elementor-widget elementor-widget-image\" data-id=\"cb535cd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25afa7c e-con-full e-flex e-con e-child\" data-id=\"25afa7c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e98612 elementor-widget elementor-widget-heading\" data-id=\"7e98612\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. B Raghavendra Charan Navada<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5c5c99 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d5c5c99\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Lawyer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Legal Advisor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c03b51 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"2c03b51\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-15863aa e-con-full e-flex e-con e-child\" data-id=\"15863aa\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3843900 elementor-widget elementor-widget-image\" data-id=\"3843900\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Mr.-Pravin-Kumar.png\" class=\"attachment-full size-full wp-image-22775\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56608ef e-con-full e-flex e-con e-child\" data-id=\"56608ef\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bb6c72 elementor-widget elementor-widget-heading\" data-id=\"9bb6c72\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Pravin Kumar<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e22c018 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e22c018\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b64bef0 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"b64bef0\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b1c061c e-con-full e-flex e-con e-child\" data-id=\"b1c061c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-829cfd0 elementor-widget elementor-widget-image\" data-id=\"829cfd0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf9cdf1 e-con-full e-flex e-con e-child\" data-id=\"bf9cdf1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22c5623 elementor-widget elementor-widget-heading\" data-id=\"22c5623\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Raksha <\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c13bb8 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5c13bb8\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c10ac2 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"3c10ac2\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fa93bdb e-con-full e-flex e-con e-child\" data-id=\"fa93bdb\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98fcfeb elementor-widget elementor-widget-image\" data-id=\"98fcfeb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38df70b e-con-full e-flex e-con e-child\" data-id=\"38df70b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11d0bb6 elementor-widget elementor-widget-heading\" data-id=\"11d0bb6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Adithi (4MK25BA001) <\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd3469e elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"fd3469e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f35f7e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"1f35f7e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-df2622c e-con-full e-flex e-con e-child\" data-id=\"df2622c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-495d871 elementor-widget elementor-widget-image\" data-id=\"495d871\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-530d3f8 e-con-full e-flex e-con e-child\" data-id=\"530d3f8\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1453981 elementor-widget elementor-widget-heading\" data-id=\"1453981\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Aneesh B.S (4MK25MC005) <\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b3f84d elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2b3f84d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a602b17 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"a602b17\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e6f4e34 e-con-full e-flex e-con e-child\" data-id=\"e6f4e34\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ff0547 elementor-widget elementor-widget-image\" data-id=\"7ff0547\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e3fdb2 e-con-full e-flex e-con e-child\" data-id=\"0e3fdb2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d9efa75 elementor-widget elementor-widget-heading\" data-id=\"d9efa75\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Bhakthi (4MK24EC009)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2b70f1 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c2b70f1\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce65a15 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"ce65a15\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5b72066 e-con-full e-flex e-con e-child\" data-id=\"5b72066\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c5e47b elementor-widget elementor-widget-image\" data-id=\"4c5e47b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-98fed51 e-con-full e-flex e-con e-child\" data-id=\"98fed51\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d47a1f elementor-widget elementor-widget-heading\" data-id=\"2d47a1f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Vaishnavi  (4MK23EC049)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ba8ce7 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5ba8ce7\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be57ad9 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"be57ad9\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7c3fb32 e-con-full e-flex e-con e-child\" data-id=\"7c3fb32\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9de726b elementor-widget elementor-widget-image\" data-id=\"9de726b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f79391 e-con-full e-flex e-con e-child\" data-id=\"6f79391\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7df5b91 elementor-widget elementor-widget-heading\" data-id=\"7df5b91\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Karuna R Gowda (4MK23CS046)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7a7f31 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b7a7f31\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a468d2c e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"a468d2c\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5129cb0 e-con-full e-flex e-con e-child\" data-id=\"5129cb0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27a8f5a elementor-widget elementor-widget-image\" data-id=\"27a8f5a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cbde49 e-con-full e-flex e-con e-child\" data-id=\"3cbde49\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bca6ebf elementor-widget elementor-widget-heading\" data-id=\"bca6ebf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Abhilash Telkar (4MK23AI001)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04a685e elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"04a685e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23a627b e-flex e-con-boxed e-con e-parent\" data-id=\"23a627b\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99a5f3e elementor-widget elementor-widget-heading\" data-id=\"99a5f3e\" data-element_type=\"widget\" id=\"anitRagging\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anti-Ragging Committee<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ffbb4de e-flex e-con-boxed e-con e-parent\" data-id=\"ffbb4de\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-acc4d81 elementor-widget elementor-widget-text-editor\" data-id=\"acc4d81\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Preamble:<\/strong><br \/>MIT gives prominence and emphasis on maintaining a ragging-free campus. Anti-Ragging Committee is a statutory committee constituted with Principal as Chairman, Vice Principal, Dean-Student Welfare, senior faculty members, student representatives, local Police Official as members. The committee is responsible for anti-ragging policy formulation, alignment, and implementation; creating awareness, monitoring ragging activities through squads, responding and taking action in case of any ragging activities.<\/p><p><strong>Objectives:<\/strong><br \/>1. To make the college campus a ragging free campus and support the student community.<br \/>2. To create awareness activities and programmes among the students on the seriousness and consequences if they get involved in ragging<br \/>3. To be vigilant and closely observe our students against involving in any form of ragging on the campus and hostel premises<br \/>4. To take strict and stringent action if any act of ragging is observed<\/p><p><strong>Policy:<\/strong><br \/>Our Policy stems on the fact that \u201cRAGGING IS A CRIMINAL OFFENCE\u201d. As per the orders of the Supreme Court of India, Government of India, UGC, AICTE, Government of Karnataka and VTU, ragging is a cognizable criminal offence punishable with non-bailable imprisonment and holds the Principal responsible for making the College ragging-free. Students should not indulge in ragging or support ragging directly or indirectly in whatsoever manner. Severe action will be initiated against those indulging in ragging or supporting ragging.<\/p><p>&#8220;Ragging&#8221; means causing, inducing, compelling or forcing a student, whether by way of a practical joke or otherwise, to do any act which detracts from human dignity or violates his person or exposes him to ridicule or to forbear from doing any lawful act, by intimidating, wrongfully restraining, wrongfully confining or injuring him or by using criminal force to him or by holding out to him any threat of such intimidation, wrongful restraint, wrongful confinement, injury or the use of criminal offence.<\/p><p>Students are severely warned that: Ragging of any kind is strictly prohibited by law inside the campus and outside. The offence of ragging is punishable under sections 109, 110, 111, 112, 113, 114, 115, 116, 302, 305, 306, 339, 340, 341, 342, 343, 344, 346, 347, 354, 359, 368, 448, 451 and 506 of Indian penal code (IPC) and section 116 of the Karnataka Education Act, 1983. The offenders will be liable for one or all of the following punitive actions:<br \/>\u2022 Photographs of offenders will not only be displayed on the notice board, but also published in newspapers.<br \/>\u2022 Offenders cannot appear for university examinations.<br \/>\u2022 Names of offenders will be sent to VTU, which will record the fact in the marks card.<br \/>\u2022 Offenders will be dismissed from the College and the hostel, and reported to the police.<\/p><p>There are no such things as friendly ragging or mild ragging. All forms of ragging are de-humanizing and go against the core of the value system which our students must develop. The College will take serious actions against those involved in ragging or supporting ragging.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba5504b e-flex e-con-boxed e-con e-parent\" data-id=\"ba5504b\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78348b8 elementor-widget elementor-widget-shortcode\" data-id=\"78348b8\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"container\" data-elementor-id=\"19958\" class=\"elementor elementor-19958\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74ba3a7c e-grid e-con-boxed e-con e-parent\" data-id=\"74ba3a7c\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;grid&quot;,&quot;grid_columns_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;3&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;content_width&quot;:&quot;boxed&quot;,&quot;grid_outline&quot;:&quot;yes&quot;,&quot;grid_columns_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_columns_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;grid_rows_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_auto_flow&quot;:&quot;row&quot;,&quot;grid_auto_flow_tablet&quot;:&quot;row&quot;,&quot;grid_auto_flow_mobile&quot;:&quot;row&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5c1851bc e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"5c1851bc\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-79cd7efd e-con-full e-flex e-con e-child\" data-id=\"79cd7efd\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72037ae7 elementor-widget elementor-widget-image\" data-id=\"72037ae7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50848.png\" class=\"attachment-full size-full wp-image-20019\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ec11fa3 e-con-full e-flex e-con e-child\" data-id=\"7ec11fa3\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63db0ef8 elementor-widget elementor-widget-heading\" data-id=\"63db0ef8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Ramakrishna Hegde<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58d7b5a4 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"58d7b5a4\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Principal<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Chairman<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 9448107623<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4546d1aa e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"4546d1aa\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ce67786 e-con-full e-flex e-con e-child\" data-id=\"ce67786\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1437369e elementor-widget elementor-widget-image\" data-id=\"1437369e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c3c5d18 e-con-full e-flex e-con e-child\" data-id=\"2c3c5d18\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-733ecc3b elementor-widget elementor-widget-heading\" data-id=\"733ecc3b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Subrahmanya Naik <\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-629e37b elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"629e37b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assist. Prof., BSH<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Co-ordinator<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 6363746623<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f2850f e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"9f2850f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f509002 e-con-full e-flex e-con e-child\" data-id=\"f509002\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-141dfcf elementor-widget elementor-widget-image\" data-id=\"141dfcf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a6b5ff e-con-full e-flex e-con e-child\" data-id=\"1a6b5ff\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-507c88b elementor-widget elementor-widget-heading\" data-id=\"507c88b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Manjanath Patgar<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8ed492 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d8ed492\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Chief Warden, Head Campus Maintenance, Safety &#038; Security Officer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 9901615112<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d3a56c e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"9d3a56c\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e28f9c2 e-con-full e-flex e-con e-child\" data-id=\"e28f9c2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf40936 elementor-widget elementor-widget-image\" data-id=\"cf40936\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50876.png\" class=\"attachment-full size-full wp-image-20104\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6806368 e-con-full e-flex e-con e-child\" data-id=\"6806368\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d06ad3 elementor-widget elementor-widget-heading\" data-id=\"3d06ad3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Deepak Shetty M<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-210e5ce elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"210e5ce\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HoD BSH<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 9945271662<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4082b8 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"a4082b8\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-31e505d e-con-full e-flex e-con e-child\" data-id=\"31e505d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0459752 elementor-widget elementor-widget-image\" data-id=\"0459752\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f078d38 e-con-full e-flex e-con e-child\" data-id=\"f078d38\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1dbb0fd elementor-widget elementor-widget-heading\" data-id=\"1dbb0fd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Sookshma Adiga<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2a98e3 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f2a98e3\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student Welfare CoOrdinator<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 9591474174<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-635c7aa e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"635c7aa\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ca8749c e-con-full e-flex e-con e-child\" data-id=\"ca8749c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94c5607 elementor-widget elementor-widget-image\" data-id=\"94c5607\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-1000006285.png\" class=\"attachment-full size-full wp-image-25692\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc0c19c e-con-full e-flex e-con e-child\" data-id=\"bc0c19c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2cf4b3 elementor-widget elementor-widget-heading\" data-id=\"b2cf4b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Subhashini K<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e9a2a0 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0e9a2a0\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Professor CSE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 9487092290<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-95f105b e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"95f105b\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-074c721 e-con-full e-flex e-con e-child\" data-id=\"074c721\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5323ea elementor-widget elementor-widget-image\" data-id=\"c5323ea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-1000006286.png\" class=\"attachment-full size-full wp-image-25693\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30ae97e e-con-full e-flex e-con e-child\" data-id=\"30ae97e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51f5194 elementor-widget elementor-widget-heading\" data-id=\"51f5194\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Muralidhar B K<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c73a89 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2c73a89\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., ISE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 9632169522<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f75942e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"f75942e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-64b6674 e-con-full e-flex e-con e-child\" data-id=\"64b6674\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce0600b elementor-widget elementor-widget-image\" data-id=\"ce0600b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f80922a e-con-full e-flex e-con e-child\" data-id=\"f80922a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-089ee87 elementor-widget elementor-widget-heading\" data-id=\"089ee87\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Vijayalakshmi R H<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bea48a9 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bea48a9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., CSEDS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 9686171485<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc99c65 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"bc99c65\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3d0f02a e-con-full e-flex e-con e-child\" data-id=\"3d0f02a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d23bf2a elementor-widget elementor-widget-image\" data-id=\"d23bf2a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-1000006287.png\" class=\"attachment-full size-full wp-image-25697\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f55f8a3 e-con-full e-flex e-con e-child\" data-id=\"f55f8a3\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17e7666 elementor-widget elementor-widget-heading\" data-id=\"17e7666\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Beerendra Kumar Patel<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fde4323 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"fde4323\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assoc. Prof., ECE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No :8085496462<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96fb848 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"96fb848\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a5ac82f e-con-full e-flex e-con e-child\" data-id=\"a5ac82f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc12a99 elementor-widget elementor-widget-image\" data-id=\"fc12a99\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3806d8c e-con-full e-flex e-con e-child\" data-id=\"3806d8c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4842371 elementor-widget elementor-widget-heading\" data-id=\"4842371\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. R. Naveen<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-006090e elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"006090e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Physical Edu Director<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Co-ordinator<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 8754173510<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-177a3127 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"177a3127\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5aea8a3f e-con-full e-flex e-con e-child\" data-id=\"5aea8a3f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b630432 elementor-widget elementor-widget-image\" data-id=\"7b630432\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Mr.-Pravin-Kumar.png\" class=\"attachment-full size-full wp-image-22775\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-605fa89e e-con-full e-flex e-con e-child\" data-id=\"605fa89e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dabaa7 elementor-widget elementor-widget-heading\" data-id=\"dabaa7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Pravin kumar<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d19631c elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5d19631c\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty- AL&#038;ML<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 9060588303<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7442ad0c e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"7442ad0c\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-72aa92bd e-con-full e-flex e-con e-child\" data-id=\"72aa92bd\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-529dc881 elementor-widget elementor-widget-image\" data-id=\"529dc881\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ec596f2 e-con-full e-flex e-con e-child\" data-id=\"3ec596f2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-307cdb2 elementor-widget elementor-widget-heading\" data-id=\"307cdb2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Raksha<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fffd34d elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1fffd34d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-BSH<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 7975202943<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2b6ee728 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"2b6ee728\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-23e9e0dc e-con-full e-flex e-con e-child\" data-id=\"23e9e0dc\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-434a4425 elementor-widget elementor-widget-image\" data-id=\"434a4425\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50849.png\" class=\"attachment-full size-full wp-image-20021\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-254eaa3e e-con-full e-flex e-con e-child\" data-id=\"254eaa3e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69a57162 elementor-widget elementor-widget-heading\" data-id=\"69a57162\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Mohammed Fadhel Aljunid<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-445d3953 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"445d3953\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty- CSE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 7304385644<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d6e93ba e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"2d6e93ba\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-14c0088e e-con-full e-flex e-con e-child\" data-id=\"14c0088e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3adec2e2 elementor-widget elementor-widget-image\" data-id=\"3adec2e2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50850.png\" class=\"attachment-full size-full wp-image-20023\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f0f26a0 e-con-full e-flex e-con e-child\" data-id=\"5f0f26a0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7eeaf6e8 elementor-widget elementor-widget-heading\" data-id=\"7eeaf6e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Shrinidhi<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e28a1d9 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7e28a1d9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty- CSE (DS)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 8296349591<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d240cbc e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"6d240cbc\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5711feba e-con-full e-flex e-con e-child\" data-id=\"5711feba\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-362a61ff elementor-widget elementor-widget-image\" data-id=\"362a61ff\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50881.png\" class=\"attachment-full size-full wp-image-20234\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e8864c8 e-con-full e-flex e-con e-child\" data-id=\"3e8864c8\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-187913b0 elementor-widget elementor-widget-heading\" data-id=\"187913b0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. S Mahapurush<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f73070d elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7f73070d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-ECE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 9880254572<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-149a6c62 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"149a6c62\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7613a948 e-con-full e-flex e-con e-child\" data-id=\"7613a948\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40c7c328 elementor-widget elementor-widget-image\" data-id=\"40c7c328\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50851.png\" class=\"attachment-full size-full wp-image-20025\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22e1d81b e-con-full e-flex e-con e-child\" data-id=\"22e1d81b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c2ddab4 elementor-widget elementor-widget-heading\" data-id=\"5c2ddab4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. G. Lakshmi<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fe9e453 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7fe9e453\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-ISE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 8921897549<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49c38a5d e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"49c38a5d\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4c7d370d e-con-full e-flex e-con e-child\" data-id=\"4c7d370d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e74aab6 elementor-widget elementor-widget-image\" data-id=\"4e74aab6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50853.png\" class=\"attachment-full size-full wp-image-20026\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b4d5f8b e-con-full e-flex e-con e-child\" data-id=\"4b4d5f8b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-622121e9 elementor-widget elementor-widget-heading\" data-id=\"622121e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Poornima R Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f232a7e elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6f232a7e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty- MBA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 9071912619<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-359b7bd9 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"359b7bd9\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-47f4011b e-con-full e-flex e-con e-child\" data-id=\"47f4011b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29c4e4d0 elementor-widget elementor-widget-image\" data-id=\"29c4e4d0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fafd739 e-con-full e-flex e-con e-child\" data-id=\"7fafd739\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70951ad5 elementor-widget elementor-widget-heading\" data-id=\"70951ad5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Supritha Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2be4a6be elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2be4a6be\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: GH-warden<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 7022260214<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66a9b026 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"66a9b026\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-57a7595c e-con-full e-flex e-con e-child\" data-id=\"57a7595c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66556fd5 elementor-widget elementor-widget-image\" data-id=\"66556fd5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f3f4e52 e-con-full e-flex e-con e-child\" data-id=\"3f3f4e52\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35599395 elementor-widget elementor-widget-heading\" data-id=\"35599395\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Prabhu B<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-786bc87c elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"786bc87c\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: BH-warden<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 7760327082<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99e18c9 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"99e18c9\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7732619 e-con-full e-flex e-con e-child\" data-id=\"7732619\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14ec67f elementor-widget elementor-widget-image\" data-id=\"14ec67f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-876e59c e-con-full e-flex e-con e-child\" data-id=\"876e59c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba64985 elementor-widget elementor-widget-heading\" data-id=\"ba64985\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Niranjan Gowda<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8d741a elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e8d741a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Sub-Inspector Kundapura Gramantara Police<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 8722633945<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-71dfdef e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"71dfdef\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-21d2604 e-con-full e-flex e-con e-child\" data-id=\"21d2604\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-04aa812 elementor-widget elementor-widget-image\" data-id=\"04aa812\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae59351 e-con-full e-flex e-con e-child\" data-id=\"ae59351\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f649c4b elementor-widget elementor-widget-heading\" data-id=\"f649c4b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. B Raghavendra Charan Navada<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e86e0a elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0e86e0a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Legal Advisor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 9845224539<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b1a1558 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"4b1a1558\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-10773ea9 e-con-full e-flex e-con e-child\" data-id=\"10773ea9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4456f2b elementor-widget elementor-widget-image\" data-id=\"4456f2b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49857165 e-con-full e-flex e-con e-child\" data-id=\"49857165\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ed605dc elementor-widget elementor-widget-heading\" data-id=\"6ed605dc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Aliya 1 year CSE-A Sec<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-585481e8 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"585481e8\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 7259600710<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4cb2c5a9 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"4cb2c5a9\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-572ecba5 e-con-full e-flex e-con e-child\" data-id=\"572ecba5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15b24ba7 elementor-widget elementor-widget-image\" data-id=\"15b24ba7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43575fa1 e-con-full e-flex e-con e-child\" data-id=\"43575fa1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5dc0e177 elementor-widget elementor-widget-heading\" data-id=\"5dc0e177\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Tejas\n1 year CSE (AL&#038;ML) D Sec<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c5830f2 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6c5830f2\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M15.3727 3.41573C12.0378 0.194757 6.75067 0.194757 3.41574 3.41573C0.113896 6.8344 0.208593 12.2824 3.62726 15.5843C6.96218 18.8052 12.2493 18.8052 15.5843 15.5843C18.8861 12.1656 18.7914 6.71758 15.3727 3.41573ZM15.1798 15.1798L15.1769 15.1769C12.0388 18.3122 6.95321 18.3099 3.81793 15.1718C0.682648 12.0336 0.684967 6.94806 3.8231 3.81277C6.96124 0.677486 12.0468 0.679805 15.1821 3.81791C15.9278 4.56428 16.5191 5.45023 16.9223 6.42518C17.3255 7.40013 17.5327 8.44496 17.532 9.5C17.5321 10.5548 17.3244 11.5993 16.9208 12.5739C16.5172 13.5484 15.9256 14.4339 15.1798 15.1798Z\" fill=\"#333333\"><\/path><path d=\"M14.3336 11.9499L12.7215 10.3435C12.3556 9.97674 11.7617 9.97604 11.3949 10.3419L11.3933 10.3435L10.4697 11.2672C10.4358 11.3011 10.3911 11.322 10.3433 11.3262C10.2956 11.3304 10.2479 11.3176 10.2086 11.2901C9.70309 10.9368 9.22983 10.5394 8.79444 10.1025C8.40449 9.71346 8.04576 9.29431 7.72158 8.84895C7.69315 8.81023 7.67954 8.76261 7.68322 8.71471C7.6869 8.66682 7.70763 8.62184 7.74165 8.58792L8.68828 7.64129C9.05375 7.27511 9.05375 6.68218 8.68828 6.316L7.07615 4.70387C6.70465 4.34871 6.1195 4.34871 5.74801 4.70387L5.23741 5.21446C4.46629 5.97691 4.19101 7.10904 4.52599 8.14042C4.77597 8.895 5.12929 9.61131 5.57589 10.2689C5.97794 10.8718 6.4392 11.433 6.95281 11.9442C7.5112 12.5065 8.12975 13.0058 8.79729 13.433C9.53112 13.9118 10.3369 14.2701 11.1839 14.4943C11.4017 14.548 11.6252 14.575 11.8494 14.5746C12.6183 14.5699 13.3538 14.2604 13.8947 13.7141L14.3336 13.2752C14.6991 12.909 14.6991 12.3161 14.3336 11.9499ZM13.9274 12.8839L13.9262 12.8851L13.9291 12.8765L13.4902 13.3154C13.2129 13.5961 12.868 13.8007 12.4886 13.9092C12.1092 14.0177 11.7082 14.0266 11.3244 13.935C10.538 13.7245 9.79035 13.3894 9.10989 12.9425C8.47769 12.5384 7.89185 12.0661 7.36293 11.534C6.87628 11.0509 6.43904 10.5204 6.05771 9.95052C5.64061 9.3373 5.31045 8.66926 5.07666 7.96545C4.94525 7.56006 4.92931 7.12608 5.03065 6.71215C5.13198 6.29821 5.34657 5.92067 5.65038 5.62182L6.16098 5.11123C6.30294 4.96863 6.53362 4.96812 6.67618 5.11009L6.67732 5.11123L8.28945 6.72336C8.43205 6.86532 8.43256 7.096 8.2906 7.23856L8.28945 7.23971L7.34282 8.18634C7.07121 8.455 7.03705 8.88193 7.26251 9.19036C7.60491 9.66024 7.98378 10.1024 8.39561 10.5128C8.85478 10.9739 9.35396 11.3934 9.88726 11.7664C10.1954 11.9813 10.6132 11.9451 10.8798 11.6803L11.7948 10.7509C11.9368 10.6083 12.1675 10.6078 12.31 10.7497L12.3112 10.7509L13.9262 12.3688C14.0688 12.5107 14.0694 12.7413 13.9274 12.8839Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobile No : 7204331055<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14506df e-flex e-con-boxed e-con e-parent\" data-id=\"14506df\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ee5bf0 elementor-widget elementor-widget-heading\" data-id=\"9ee5bf0\" data-element_type=\"widget\" id=\"scst\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SC\/ST  Cell<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a43534 e-flex e-con-boxed e-con e-parent\" data-id=\"5a43534\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d76c735 elementor-widget elementor-widget-text-editor\" data-id=\"d76c735\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Preamble:<\/strong><br \/>The Constitution of the country, promulgated in 1950, recognizes the scheduled castes and the scheduled tribes as the two most backward groups in Indian society needing special protection. India, a country of diversity, a mix of different religions, castes and cultures is characterized by a highly-entrenched system of social stratification. They include all the castes, races or tribes, which have been socially, economically and educationally backward. Therefore, we, as an institute, have constituted an SC\/ST Cell which would help in eliminating the social disparities in compliance with the Government of India, AICTE, UGC and VTU guidelines from time to time. Also, we try to sort out their problems related to academics, personal and social life. Also, we create awareness and assist to avail scholarships.<\/p><p><strong>Objectives:<\/strong> <br \/>1. Be an entity that disseminates information related to SC\/ST reservation, implemented in the institute as per Indian Government Policy. <br \/>2.Provide a platform for registering complaints, issues \/ grievances of SC\/ST candidates. <br \/>3.To implement, monitor and evaluate continuously the reservation policy in the University and plan measures for effective implementation of the policy and programme of the Government and UGC. <br \/>4. To guide the SC\/ST students of the University, to optimally utilize the benefits of the schemes offered by the State Government, Government of India (GOI) and UGC <br \/>5. To provide them discriminative free campus and help them to excel in academics and placements.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e7b51e e-flex e-con-boxed e-con e-parent\" data-id=\"3e7b51e\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5384c6 elementor-widget elementor-widget-shortcode\" data-id=\"b5384c6\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"container\" data-elementor-id=\"25706\" class=\"elementor elementor-25706\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e533000 e-grid e-con-boxed e-con e-parent\" data-id=\"e533000\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;grid&quot;,&quot;grid_columns_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;3&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;content_width&quot;:&quot;boxed&quot;,&quot;grid_outline&quot;:&quot;yes&quot;,&quot;grid_columns_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_columns_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;grid_rows_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_auto_flow&quot;:&quot;row&quot;,&quot;grid_auto_flow_tablet&quot;:&quot;row&quot;,&quot;grid_auto_flow_mobile&quot;:&quot;row&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7ab3f735 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"7ab3f735\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-51e8e2a7 e-con-full e-flex e-con e-child\" data-id=\"51e8e2a7\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a60a625 elementor-widget elementor-widget-image\" data-id=\"7a60a625\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50848.png\" class=\"attachment-full size-full wp-image-20019\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-354b756f e-con-full e-flex e-con e-child\" data-id=\"354b756f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-335e23d0 elementor-widget elementor-widget-heading\" data-id=\"335e23d0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Ramakrishna Hegde<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22a40522 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"22a40522\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Principal, MITK<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Chairman<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e372bed e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"4e372bed\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7875a337 e-con-full e-flex e-con e-child\" data-id=\"7875a337\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c19537 elementor-widget elementor-widget-image\" data-id=\"5c19537\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50854.png\" class=\"attachment-full size-full wp-image-20028\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e9aa115 e-con-full e-flex e-con e-child\" data-id=\"2e9aa115\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-534954fb elementor-widget elementor-widget-heading\" data-id=\"534954fb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Manjunath R. Lamani<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ed45b48 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6ed45b48\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD CSE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation: Co-Ordinator<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fbbec0d e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"4fbbec0d\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-265689a6 e-con-full e-flex e-con e-child\" data-id=\"265689a6\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-541731b8 elementor-widget elementor-widget-image\" data-id=\"541731b8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50855.png\" class=\"attachment-full size-full wp-image-20029\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b1b6e2c e-con-full e-flex e-con e-child\" data-id=\"4b1b6e2c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ac319e4 elementor-widget elementor-widget-heading\" data-id=\"6ac319e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Prashant Naik<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ce3a44c elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7ce3a44c\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty- AI&#038;ML<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d97869c e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"d97869c\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-273eac0 e-con-full e-flex e-con e-child\" data-id=\"273eac0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe42e80 elementor-widget elementor-widget-image\" data-id=\"fe42e80\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50855.png\" class=\"attachment-full size-full wp-image-20029\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b57610d e-con-full e-flex e-con e-child\" data-id=\"b57610d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c502e0 elementor-widget elementor-widget-heading\" data-id=\"4c502e0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Prashant Naik<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7446591 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7446591\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty- AI&#038;ML<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-419596bf e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"419596bf\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-382278b4 e-con-full e-flex e-con e-child\" data-id=\"382278b4\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-287bd958 elementor-widget elementor-widget-image\" data-id=\"287bd958\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2026\/08\/Group-1000006292.png\" class=\"attachment-full size-full wp-image-25712\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62caca4b e-con-full e-flex e-con e-child\" data-id=\"62caca4b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3578102b elementor-widget elementor-widget-heading\" data-id=\"3578102b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Kumaraswamy<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d711b0a elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1d711b0a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Associ. Prof., AI&#038;ML <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e42359d e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"e42359d\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7bb0b9c e-con-full e-flex e-con e-child\" data-id=\"7bb0b9c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e0f220 elementor-widget elementor-widget-image\" data-id=\"9e0f220\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2026\/08\/Group-1000006293.png\" class=\"attachment-full size-full wp-image-25713\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6cccab1 e-con-full e-flex e-con e-child\" data-id=\"6cccab1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1b4f02 elementor-widget elementor-widget-heading\" data-id=\"e1b4f02\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Dharani B Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c06edc elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6c06edc\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., BSH<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd77516 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"fd77516\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c8597fe e-con-full e-flex e-con e-child\" data-id=\"c8597fe\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dfccc3 elementor-widget elementor-widget-image\" data-id=\"2dfccc3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2026\/08\/Group-1000006294.png\" class=\"attachment-full size-full wp-image-25714\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a6ab37 e-con-full e-flex e-con e-child\" data-id=\"5a6ab37\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a3bbc7 elementor-widget elementor-widget-heading\" data-id=\"4a3bbc7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Mushra<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc96f59 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dc96f59\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., CSEDS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-424f9822 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"424f9822\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-212af8ea e-con-full e-flex e-con e-child\" data-id=\"212af8ea\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-670a09ae elementor-widget elementor-widget-image\" data-id=\"670a09ae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5dcedcfd e-con-full e-flex e-con e-child\" data-id=\"5dcedcfd\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7de0ffeb elementor-widget elementor-widget-heading\" data-id=\"7de0ffeb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. R. Naveen<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6940250 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6940250\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Physical education Director<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-340134d2 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"340134d2\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-346fd21 e-con-full e-flex e-con e-child\" data-id=\"346fd21\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49706ddc elementor-widget elementor-widget-image\" data-id=\"49706ddc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50856.png\" class=\"attachment-full size-full wp-image-20030\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a8177df e-con-full e-flex e-con e-child\" data-id=\"1a8177df\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71724366 elementor-widget elementor-widget-heading\" data-id=\"71724366\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Ashwini<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ef119b8 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1ef119b8\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty- BSH<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-638727d4 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"638727d4\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5d55fe36 e-con-full e-flex e-con e-child\" data-id=\"5d55fe36\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57f4db2a elementor-widget elementor-widget-image\" data-id=\"57f4db2a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50857.png\" class=\"attachment-full size-full wp-image-20032\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6fe33c8 e-con-full e-flex e-con e-child\" data-id=\"6fe33c8\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f8b84fa elementor-widget elementor-widget-heading\" data-id=\"1f8b84fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Divya K<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dae34df elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6dae34df\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-ECE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c4d9afa e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"1c4d9afa\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1dc4a2cf e-con-full e-flex e-con e-child\" data-id=\"1dc4a2cf\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-367cffce elementor-widget elementor-widget-image\" data-id=\"367cffce\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2026\/08\/Group-1000006295.png\" class=\"attachment-full size-full wp-image-25715\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66c8ed32 e-con-full e-flex e-con e-child\" data-id=\"66c8ed32\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21f56c7d elementor-widget elementor-widget-heading\" data-id=\"21f56c7d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Sanketh<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15ce2046 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"15ce2046\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., ISE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aad71d6 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"aad71d6\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-12b052f e-con-full e-flex e-con e-child\" data-id=\"12b052f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01116f7 elementor-widget elementor-widget-image\" data-id=\"01116f7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c6a7bda e-con-full e-flex e-con e-child\" data-id=\"c6a7bda\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51e87f2 elementor-widget elementor-widget-heading\" data-id=\"51e87f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Raja<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aab34c7 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"aab34c7\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-ISE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-426aff11 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"426aff11\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-42462028 e-con-full e-flex e-con e-child\" data-id=\"42462028\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39625d88 elementor-widget elementor-widget-image\" data-id=\"39625d88\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50859.png\" class=\"attachment-full size-full wp-image-20033\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32711599 e-con-full e-flex e-con e-child\" data-id=\"32711599\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5135fedd elementor-widget elementor-widget-heading\" data-id=\"5135fedd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Nagaveni<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb9d74f elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6cb9d74f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-MBA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-438ae60 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"438ae60\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1fe37f5b e-con-full e-flex e-con e-child\" data-id=\"1fe37f5b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18618ff3 elementor-widget elementor-widget-image\" data-id=\"18618ff3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2026\/08\/Group-1000006296.png\" class=\"attachment-full size-full wp-image-25716\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40c41d45 e-con-full e-flex e-con e-child\" data-id=\"40c41d45\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2693d4d6 elementor-widget elementor-widget-heading\" data-id=\"2693d4d6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Prasanna Kumara<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a0a32db elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3a0a32db\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., MCA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bdc2949 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"bdc2949\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-278f864 e-con-full e-flex e-con e-child\" data-id=\"278f864\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-affa306 elementor-widget elementor-widget-image\" data-id=\"affa306\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1812db2 e-con-full e-flex e-con e-child\" data-id=\"1812db2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20c2832 elementor-widget elementor-widget-heading\" data-id=\"20c2832\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Smitha Hoblidar<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad1f952 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ad1f952\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Office Superintendent<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7821a004 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"7821a004\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7680afab e-con-full e-flex e-con e-child\" data-id=\"7680afab\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74328124 elementor-widget elementor-widget-image\" data-id=\"74328124\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2149d9ac e-con-full e-flex e-con e-child\" data-id=\"2149d9ac\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31e68a0a elementor-widget elementor-widget-heading\" data-id=\"31e68a0a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Ankitha N Bhandary<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51c8a17a elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"51c8a17a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-MCA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75ee4f90 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"75ee4f90\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-59f67eb7 e-con-full e-flex e-con e-child\" data-id=\"59f67eb7\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63acfd13 elementor-widget elementor-widget-image\" data-id=\"63acfd13\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66899fb0 e-con-full e-flex e-con e-child\" data-id=\"66899fb0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64762544 elementor-widget elementor-widget-heading\" data-id=\"64762544\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Raveendra (4MK25BA086<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-401e615e elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"401e615e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dfb0082 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"dfb0082\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cf9d337 e-con-full e-flex e-con e-child\" data-id=\"cf9d337\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b797ef4 elementor-widget elementor-widget-image\" data-id=\"b797ef4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35065a9 e-con-full e-flex e-con e-child\" data-id=\"35065a9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25b57d4 elementor-widget elementor-widget-heading\" data-id=\"25b57d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Sagar (4MK25MC038)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b5d125 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3b5d125\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e831ff0 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"e831ff0\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3500a0b e-con-full e-flex e-con e-child\" data-id=\"3500a0b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7eabff4 elementor-widget elementor-widget-image\" data-id=\"7eabff4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9003c1b e-con-full e-flex e-con e-child\" data-id=\"9003c1b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce4b644 elementor-widget elementor-widget-heading\" data-id=\"ce4b644\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Mallika (4MK23CS053)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61db887 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"61db887\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6cf9544b e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"6cf9544b\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3103e585 e-con-full e-flex e-con e-child\" data-id=\"3103e585\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-755b751a elementor-widget elementor-widget-image\" data-id=\"755b751a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ad79780 e-con-full e-flex e-con e-child\" data-id=\"5ad79780\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69cc8031 elementor-widget elementor-widget-heading\" data-id=\"69cc8031\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Shabari (4MK24CS086)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dbdb3b2 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7dbdb3b2\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b881975 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"6b881975\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7282629 e-con-full e-flex e-con e-child\" data-id=\"7282629\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2140b941 elementor-widget elementor-widget-image\" data-id=\"2140b941\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5188e978 e-con-full e-flex e-con e-child\" data-id=\"5188e978\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb7e407 elementor-widget elementor-widget-heading\" data-id=\"3eb7e407\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Divyashree S (4MK23EC017)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39a9d4e3 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"39a9d4e3\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2811b8d9 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"2811b8d9\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-658183e1 e-con-full e-flex e-con e-child\" data-id=\"658183e1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6db211d6 elementor-widget elementor-widget-image\" data-id=\"6db211d6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70300c72 e-con-full e-flex e-con e-child\" data-id=\"70300c72\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26666356 elementor-widget elementor-widget-heading\" data-id=\"26666356\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Bhuvana R (4MK24EC010) <\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45f3f15f elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"45f3f15f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a916227 e-flex e-con-boxed e-con e-parent\" data-id=\"a916227\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fa7bf36 e-flex e-con-boxed e-con e-child\" data-id=\"fa7bf36\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bdf9bb0 elementor-widget elementor-widget-heading\" data-id=\"bdf9bb0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OBC Cell<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c5c1548 e-flex e-con-boxed e-con e-child\" data-id=\"c5c1548\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e950cc2 elementor-widget elementor-widget-text-editor\" data-id=\"e950cc2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Preamble:<\/strong><br \/>The Other Backward Classes (OBC) Cell of the institution has been established in accordance with the directives of the Government of India and the guidelines of the All India Council for Technical Education (AICTE) to ensure the effective implementation of policies and programs for the welfare of OBC students, faculty, and staff. The cell is committed to promoting social justice, equality, and inclusiveness within the campus by facilitating access to academic, financial, and administrative support systems for members of the OBC community. It acts as a channel of communication between the students and the institutional authorities to address concerns, grievances, and suggestions related to OBC welfare.<\/p><p><strong>Objectives:<\/strong> <br \/>1. To ensure effective implementation of the policies and programs of the Government of India and State Governments pertaining to the welfare of Other Backward Classes (OBC) in admissions, scholarships, and employment.<br \/>2. To facilitate guidance, counselling , and support services for OBC students in academic, financial, and personal matters to promote their overall development and ensure equal opportunities.<br \/>3. To create awareness and conduct sensitization programs among staff and students on issues related to social justice, equity, and inclusion for the upliftment of the OBC community.<br \/>4. To act as a grievance redressal body for OBC students, faculty, and staff to address any complaints related to discrimination, non-implementation of reservation policies, or denial of entitlements.<br \/>5. To monitor and maintain records related to admissions, scholarships, and placements of OBC students, ensuring that all statutory provisions and institutional measures are properly implemented and documented<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22c64cb e-flex e-con-boxed e-con e-child\" data-id=\"22c64cb\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a640fd elementor-widget elementor-widget-shortcode\" data-id=\"8a640fd\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"container\" data-elementor-id=\"19934\" class=\"elementor elementor-19934\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74a5ed1a e-grid e-con-boxed e-con e-parent\" data-id=\"74a5ed1a\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;grid&quot;,&quot;grid_columns_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;3&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;content_width&quot;:&quot;boxed&quot;,&quot;grid_outline&quot;:&quot;yes&quot;,&quot;grid_columns_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_columns_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;grid_rows_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_auto_flow&quot;:&quot;row&quot;,&quot;grid_auto_flow_tablet&quot;:&quot;row&quot;,&quot;grid_auto_flow_mobile&quot;:&quot;row&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b965498 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"b965498\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5d2ba15 e-con-full e-flex e-con e-child\" data-id=\"5d2ba15\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49b2535 elementor-widget elementor-widget-image\" data-id=\"49b2535\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50848.png\" class=\"attachment-full size-full wp-image-20019\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c2e6efa e-con-full e-flex e-con e-child\" data-id=\"c2e6efa\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9fe5b5b elementor-widget elementor-widget-heading\" data-id=\"9fe5b5b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Ramakrishna Hegde<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8bfc85 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d8bfc85\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Principal, MITK<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Chairman<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15f813d e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"15f813d\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c4ec733 e-con-full e-flex e-con e-child\" data-id=\"c4ec733\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28f6c5f elementor-widget elementor-widget-image\" data-id=\"28f6c5f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-1000006289.png\" class=\"attachment-full size-full wp-image-25700\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec5aec0 e-con-full e-flex e-con e-child\" data-id=\"ec5aec0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b38750e elementor-widget elementor-widget-heading\" data-id=\"b38750e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Nirmal Kumar Nigam<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85a045b elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"85a045b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., AI&#038;ML<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Co-Ordinator<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5843e7c9 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"5843e7c9\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1307fc88 e-con-full e-flex e-con e-child\" data-id=\"1307fc88\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2551ed11 elementor-widget elementor-widget-image\" data-id=\"2551ed11\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50863.png\" class=\"attachment-full size-full wp-image-20037\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f42af80 e-con-full e-flex e-con e-child\" data-id=\"5f42af80\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6349c8c2 elementor-widget elementor-widget-heading\" data-id=\"6349c8c2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Smithashree K<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebe47b5 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ebe47b5\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., CSE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0fd6b6f e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"0fd6b6f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e880c7d e-con-full e-flex e-con e-child\" data-id=\"e880c7d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-363e07a elementor-widget elementor-widget-image\" data-id=\"363e07a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/11\/Group-50870.png\" class=\"attachment-full size-full wp-image-20050\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33cdcfd e-con-full e-flex e-con e-child\" data-id=\"33cdcfd\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebcf75d elementor-widget elementor-widget-heading\" data-id=\"ebcf75d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. J. Prakash<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef5ce86 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ef5ce86\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD-ISE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation: Coordinator<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59332822 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"59332822\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-70ce3d1e e-con-full e-flex e-con e-child\" data-id=\"70ce3d1e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d0f4b2 elementor-widget elementor-widget-image\" data-id=\"7d0f4b2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50860.png\" class=\"attachment-full size-full wp-image-20035\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-565695c2 e-con-full e-flex e-con e-child\" data-id=\"565695c2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1156024f elementor-widget elementor-widget-heading\" data-id=\"1156024f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Farana Mohammad Imran<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34c2a12 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"34c2a12\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., CSE -DS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation: Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d0d71ad e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"d0d71ad\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8d3dc28 e-con-full e-flex e-con e-child\" data-id=\"8d3dc28\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4328063 elementor-widget elementor-widget-image\" data-id=\"4328063\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-1000006290.png\" class=\"attachment-full size-full wp-image-25701\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-903020b e-con-full e-flex e-con e-child\" data-id=\"903020b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3d7f2e elementor-widget elementor-widget-heading\" data-id=\"a3d7f2e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Ajitesh <\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c962ab elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6c962ab\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., ECE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation: Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0c29fa e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"c0c29fa\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-14b6695 e-con-full e-flex e-con e-child\" data-id=\"14b6695\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-352ef7c elementor-widget elementor-widget-image\" data-id=\"352ef7c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-1000006291.png\" class=\"attachment-full size-full wp-image-25702\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b3b58b e-con-full e-flex e-con e-child\" data-id=\"7b3b58b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c54466 elementor-widget elementor-widget-heading\" data-id=\"7c54466\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Drishya Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84d7130 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"84d7130\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., ISE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation: Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ae60ca e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"6ae60ca\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f55c2ed e-con-full e-flex e-con e-child\" data-id=\"f55c2ed\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6da4fbe elementor-widget elementor-widget-image\" data-id=\"6da4fbe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-171cfd1 e-con-full e-flex e-con e-child\" data-id=\"171cfd1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26913eb elementor-widget elementor-widget-heading\" data-id=\"26913eb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Chaithali<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9c907d elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d9c907d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., MBA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation: Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-daca0ef e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"daca0ef\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9a2f427 e-con-full e-flex e-con e-child\" data-id=\"9a2f427\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-774af46 elementor-widget elementor-widget-image\" data-id=\"774af46\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f499f43 e-con-full e-flex e-con e-child\" data-id=\"f499f43\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ceff13 elementor-widget elementor-widget-heading\" data-id=\"1ceff13\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dayananda G Naik  (4MK25BA021)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a49c74 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4a49c74\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation: Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5992098 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"5992098\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-879cec8 e-con-full e-flex e-con e-child\" data-id=\"879cec8\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97294e9 elementor-widget elementor-widget-image\" data-id=\"97294e9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40914aa e-con-full e-flex e-con e-child\" data-id=\"40914aa\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fdc1d5 elementor-widget elementor-widget-heading\" data-id=\"7fdc1d5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Poojari Roshan R (4MK25MC027) <\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5dfcbf elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c5dfcbf\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation: Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78183b9a e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"78183b9a\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4c97c604 e-con-full e-flex e-con e-child\" data-id=\"4c97c604\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-551ab79 elementor-widget elementor-widget-image\" data-id=\"551ab79\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50862.png\" class=\"attachment-full size-full wp-image-20036\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e74ae7a e-con-full e-flex e-con e-child\" data-id=\"7e74ae7a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6922ad88 elementor-widget elementor-widget-heading\" data-id=\"6922ad88\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Neil Gladwin Dilma<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3792cc44 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3792cc44\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-MBA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e54bc23 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"3e54bc23\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-64f2858d e-con-full e-flex e-con e-child\" data-id=\"64f2858d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-562771e2 elementor-widget elementor-widget-image\" data-id=\"562771e2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50864.png\" class=\"attachment-full size-full wp-image-20038\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73fe8664 e-con-full e-flex e-con e-child\" data-id=\"73fe8664\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab35839 elementor-widget elementor-widget-heading\" data-id=\"ab35839\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Sushma Shedthi<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d890744 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4d890744\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-ECE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d49f033 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"1d49f033\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5a4890e5 e-con-full e-flex e-con e-child\" data-id=\"5a4890e5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f7e9b8e elementor-widget elementor-widget-image\" data-id=\"5f7e9b8e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/10\/Group-50865.png\" class=\"attachment-full size-full wp-image-20039\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-565f2c56 e-con-full e-flex e-con e-child\" data-id=\"565f2c56\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1cbccf49 elementor-widget elementor-widget-heading\" data-id=\"1cbccf49\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Chaithra<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72104bb8 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"72104bb8\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-BSH<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-481468f5 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"481468f5\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-795df883 e-con-full e-flex e-con e-child\" data-id=\"795df883\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44d94679 elementor-widget elementor-widget-image\" data-id=\"44d94679\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37a96b9b e-con-full e-flex e-con e-child\" data-id=\"37a96b9b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1eb6423f elementor-widget elementor-widget-heading\" data-id=\"1eb6423f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Hima (4MK24CD024)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-121cfd87 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"121cfd87\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c26627a e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"4c26627a\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-167e3398 e-con-full e-flex e-con e-child\" data-id=\"167e3398\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d50a579 elementor-widget elementor-widget-image\" data-id=\"3d50a579\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-732232af e-con-full e-flex e-con e-child\" data-id=\"732232af\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-111c9e63 elementor-widget elementor-widget-heading\" data-id=\"111c9e63\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Lavanya (4MK23CD024)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a205321 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a205321\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30e632fa e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"30e632fa\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5ac98d40 e-con-full e-flex e-con e-child\" data-id=\"5ac98d40\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36b25b elementor-widget elementor-widget-image\" data-id=\"36b25b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68c2ce0e e-con-full e-flex e-con e-child\" data-id=\"68c2ce0e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21add4cf elementor-widget elementor-widget-heading\" data-id=\"21add4cf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Darshan Chetan (4MK22CD015)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9600e2 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b9600e2\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-716f9ab e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"716f9ab\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b344805 e-con-full e-flex e-con e-child\" data-id=\"b344805\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c98cf1 elementor-widget elementor-widget-image\" data-id=\"4c98cf1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c026807 e-con-full e-flex e-con e-child\" data-id=\"c026807\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba18de6 elementor-widget elementor-widget-heading\" data-id=\"ba18de6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Manvel Anthon Mangali (4MK23EC027)<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc04578 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bc04578\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21cee48 e-flex e-con-boxed e-con e-parent\" data-id=\"21cee48\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab47466 elementor-widget elementor-widget-heading\" data-id=\"ab47466\" data-element_type=\"widget\" id=\"grievanceCell\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Grievance Redressal Cell<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-106c986 e-flex e-con-boxed e-con e-parent\" data-id=\"106c986\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cdc8949 elementor-widget elementor-widget-text-editor\" data-id=\"cdc8949\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Preamble:<\/strong> <br \/>The Grievance Redressal Cell at Moodlakatte Institute of Technology is constituted with the mission of developing a responsible and positive attitude among students in order to maintain a harmonious educational atmosphere in the College. The cell has a committee which functions as per the policy and guidelines of the University Grants Commission Grievance Redressal Regulations, 2012, All India Council for Technical Education (Redressal of Grievance of students) Regulations, 2019 and the circular \/ notices issued by UGC\/AICTE\/VTU from time to time. <br \/><br \/><strong>Objectives: <\/strong><br \/>1. To uphold the dignity of the college by ensuring healthy and peaceful atmosphere in the College trough promoting cordial relationships among the students and between students and teachers. <br \/>2. To support students to access services and benefits offered by the college without any difficulty. <br \/>3. To make teaching and supporting staff responsive, accountable and courteous in dealing with the students. <br \/>4. To investigate the reason of dissatisfaction of students <br \/>5. To ensure effective solution to the student grievances with an impartial and fair approach. <br \/>6. To encourage the students to express their grievance \/ problems freely and frankly without any fear of being victimized.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-240f1b5 e-grid e-con-boxed e-con e-parent\" data-id=\"240f1b5\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;grid&quot;,&quot;grid_columns_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;3&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;content_width&quot;:&quot;boxed&quot;,&quot;grid_outline&quot;:&quot;yes&quot;,&quot;grid_columns_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_columns_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;grid_rows_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_auto_flow&quot;:&quot;row&quot;,&quot;grid_auto_flow_tablet&quot;:&quot;row&quot;,&quot;grid_auto_flow_mobile&quot;:&quot;row&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a88d8e4 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"a88d8e4\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-54cbcdb e-con-full e-flex e-con e-child\" data-id=\"54cbcdb\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55d69d5 elementor-widget elementor-widget-image\" data-id=\"55d69d5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb73239 e-con-full e-flex e-con e-child\" data-id=\"cb73239\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35c0ef5 elementor-widget elementor-widget-heading\" data-id=\"35c0ef5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Ramakrishna Hegde<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e31d4ab elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e31d4ab\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Principal<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Chairman<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ac4d1e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"5ac4d1e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a14f74c e-con-full e-flex e-con e-child\" data-id=\"a14f74c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51b72b5 elementor-widget elementor-widget-image\" data-id=\"51b72b5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a18ad5 e-con-full e-flex e-con e-child\" data-id=\"5a18ad5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bfda1f6 elementor-widget elementor-widget-heading\" data-id=\"bfda1f6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prof. Melwin D&#8217;Souza<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fdfe9f elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1fdfe9f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Vice Principal<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Convenor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9883ba3 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"9883ba3\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-27b784a e-con-full e-flex e-con e-child\" data-id=\"27b784a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc87860 elementor-widget elementor-widget-image\" data-id=\"bc87860\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2bd7af6 e-con-full e-flex e-con e-child\" data-id=\"2bd7af6\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32a0e14 elementor-widget elementor-widget-heading\" data-id=\"32a0e14\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Ramakrishna Hegde<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f9e9a0 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1f9e9a0\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Dean-Student Welfare<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88ff0a7 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"88ff0a7\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d294a6a e-con-full e-flex e-con e-child\" data-id=\"d294a6a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea5fa76 elementor-widget elementor-widget-image\" data-id=\"ea5fa76\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e1761e3 e-con-full e-flex e-con e-child\" data-id=\"e1761e3\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8c8d0f elementor-widget elementor-widget-heading\" data-id=\"b8c8d0f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Nikhila Pai<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ad187a elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8ad187a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ef964f e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"2ef964f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-22d89bb e-con-full e-flex e-con e-child\" data-id=\"22d89bb\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2b6a79 elementor-widget elementor-widget-image\" data-id=\"c2b6a79\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f95d6c3 e-con-full e-flex e-con e-child\" data-id=\"f95d6c3\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ee01c0 elementor-widget elementor-widget-heading\" data-id=\"3ee01c0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prof. Deepak Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e611804 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e611804\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD(BSH)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e35a33 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"3e35a33\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c63646 e-con-full e-flex e-con e-child\" data-id=\"3c63646\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1664bc elementor-widget elementor-widget-image\" data-id=\"e1664bc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-879bf8b e-con-full e-flex e-con e-child\" data-id=\"879bf8b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c76c03 elementor-widget elementor-widget-heading\" data-id=\"7c76c03\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prof. Amruthamala<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a399beb elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a399beb\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Dean(T&#038;P and IR)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7ea26f e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"e7ea26f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-868a04a e-con-full e-flex e-con e-child\" data-id=\"868a04a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7dfff2 elementor-widget elementor-widget-image\" data-id=\"f7dfff2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-101322c e-con-full e-flex e-con e-child\" data-id=\"101322c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6765050 elementor-widget elementor-widget-heading\" data-id=\"6765050\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prof. Asha Kumari<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59f86e5 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"59f86e5\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-328191e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"328191e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3e522e2 e-con-full e-flex e-con e-child\" data-id=\"3e522e2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e14aebd elementor-widget elementor-widget-image\" data-id=\"e14aebd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb74564 e-con-full e-flex e-con e-child\" data-id=\"fb74564\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-512cf89 elementor-widget elementor-widget-heading\" data-id=\"512cf89\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prof. Muralidhara B K<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a40696 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1a40696\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD(CSE)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3151923 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"3151923\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c3bd9dd e-con-full e-flex e-con e-child\" data-id=\"c3bd9dd\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51ebd14 elementor-widget elementor-widget-image\" data-id=\"51ebd14\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96dbb20 e-con-full e-flex e-con e-child\" data-id=\"96dbb20\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee921a5 elementor-widget elementor-widget-heading\" data-id=\"ee921a5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Basavaraj Kambale<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc6d2b4 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dc6d2b4\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Associate Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9f397c e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"c9f397c\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-76c03bf e-con-full e-flex e-con e-child\" data-id=\"76c03bf\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0388ff7 elementor-widget elementor-widget-image\" data-id=\"0388ff7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-026ca2e e-con-full e-flex e-con e-child\" data-id=\"026ca2e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c29c05 elementor-widget elementor-widget-heading\" data-id=\"2c29c05\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Mithun Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e5ef78 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2e5ef78\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e54a84 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"6e54a84\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e817f6c e-con-full e-flex e-con e-child\" data-id=\"e817f6c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-627d2a0 elementor-widget elementor-widget-image\" data-id=\"627d2a0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82150a4 e-con-full e-flex e-con e-child\" data-id=\"82150a4\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86d716c elementor-widget elementor-widget-heading\" data-id=\"86d716c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Meghana<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbbdb5f elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"fbbdb5f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6046410 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"6046410\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8858908 e-con-full e-flex e-con e-child\" data-id=\"8858908\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8859c8 elementor-widget elementor-widget-image\" data-id=\"a8859c8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11c1669 e-con-full e-flex e-con e-child\" data-id=\"11c1669\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5dd8e3 elementor-widget elementor-widget-heading\" data-id=\"b5dd8e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Indra Vijay Singh<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a709b5 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0a709b5\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Dean R&#038;C and HOD-AI&#038;ML<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e77f26f e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"e77f26f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1d3fe78 e-con-full e-flex e-con e-child\" data-id=\"1d3fe78\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba149e8 elementor-widget elementor-widget-image\" data-id=\"ba149e8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-740f93a e-con-full e-flex e-con e-child\" data-id=\"740f93a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1c24e1 elementor-widget elementor-widget-heading\" data-id=\"c1c24e1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Varuna Kumara<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-961c484 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"961c484\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD-ECE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b3424dd e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"b3424dd\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bcfd838 e-con-full e-flex e-con e-child\" data-id=\"bcfd838\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f82509e elementor-widget elementor-widget-image\" data-id=\"f82509e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d71add2 e-con-full e-flex e-con e-child\" data-id=\"d71add2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b37cb53 elementor-widget elementor-widget-heading\" data-id=\"b37cb53\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. J. Prakash<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c304fd elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8c304fd\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD-ISE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-063f20e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"063f20e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0473b7b e-con-full e-flex e-con e-child\" data-id=\"0473b7b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2fe49e elementor-widget elementor-widget-image\" data-id=\"f2fe49e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fed9481 e-con-full e-flex e-con e-child\" data-id=\"fed9481\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d8a8b0 elementor-widget elementor-widget-heading\" data-id=\"8d8a8b0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Smithashree\n\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57f1cc4 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"57f1cc4\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-CSE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-80afc48 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"80afc48\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b472bc2 e-con-full e-flex e-con e-child\" data-id=\"b472bc2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7002748 elementor-widget elementor-widget-image\" data-id=\"7002748\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-513e632 e-con-full e-flex e-con e-child\" data-id=\"513e632\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ec91ed elementor-widget elementor-widget-heading\" data-id=\"4ec91ed\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. T. Nandhini<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c0c46c elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7c0c46c\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD-MCA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-546bfb0 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"546bfb0\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8541213 e-con-full e-flex e-con e-child\" data-id=\"8541213\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3960f9d elementor-widget elementor-widget-image\" data-id=\"3960f9d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c847fce e-con-full e-flex e-con e-child\" data-id=\"c847fce\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6979553 elementor-widget elementor-widget-heading\" data-id=\"6979553\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Chaithra<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acdfd61 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"acdfd61\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-BSH<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45b258e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"45b258e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e075498 e-con-full e-flex e-con e-child\" data-id=\"e075498\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02f40b4 elementor-widget elementor-widget-image\" data-id=\"02f40b4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39b9a9b e-con-full e-flex e-con e-child\" data-id=\"39b9a9b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e550c8 elementor-widget elementor-widget-heading\" data-id=\"7e550c8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prof. Shrinidhi\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a589bbc elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a589bbc\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty- CSE (DS)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29cb05e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"29cb05e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9b99179 e-con-full e-flex e-con e-child\" data-id=\"9b99179\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c155f1 elementor-widget elementor-widget-image\" data-id=\"3c155f1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f08cf5 e-con-full e-flex e-con e-child\" data-id=\"0f08cf5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-09cd607 elementor-widget elementor-widget-heading\" data-id=\"09cd607\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Nagaveni\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70b5ece elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"70b5ece\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty- MBA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-01c9290 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"01c9290\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-941daa2 e-con-full e-flex e-con e-child\" data-id=\"941daa2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-219c456 elementor-widget elementor-widget-image\" data-id=\"219c456\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0400196 e-con-full e-flex e-con e-child\" data-id=\"0400196\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d6fc7f elementor-widget elementor-widget-heading\" data-id=\"5d6fc7f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Sudheer\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0cb8a9 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a0cb8a9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: PRO<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ffe0eb e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"1ffe0eb\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3dace78 e-con-full e-flex e-con e-child\" data-id=\"3dace78\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9404916 elementor-widget elementor-widget-image\" data-id=\"9404916\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-544e63f e-con-full e-flex e-con e-child\" data-id=\"544e63f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-05c5df8 elementor-widget elementor-widget-heading\" data-id=\"05c5df8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Rithesh (4MK24EC402)\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1efd0e9 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1efd0e9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bfb4a4a e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"bfb4a4a\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b411a7f e-con-full e-flex e-con e-child\" data-id=\"b411a7f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87bea11 elementor-widget elementor-widget-image\" data-id=\"87bea11\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef3047b e-con-full e-flex e-con e-child\" data-id=\"ef3047b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43bc525 elementor-widget elementor-widget-heading\" data-id=\"43bc525\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Indraj A Gouda (4MK23CS041)\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70b8bfb elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"70b8bfb\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0251999 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"0251999\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-00b33d7 e-con-full e-flex e-con e-child\" data-id=\"00b33d7\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd56ddf elementor-widget elementor-widget-image\" data-id=\"fd56ddf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf4e568 e-con-full e-flex e-con e-child\" data-id=\"bf4e568\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6133864 elementor-widget elementor-widget-heading\" data-id=\"6133864\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Nandan Shetty (4MK23CS065)\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92e4529 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"92e4529\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74c1268 e-flex e-con-boxed e-con e-parent\" data-id=\"74c1268\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-445d0f9 elementor-widget elementor-widget-shortcode\" data-id=\"445d0f9\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"container\" data-elementor-id=\"20041\" class=\"elementor elementor-20041\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-635bcbe2 e-grid e-con-boxed e-con e-parent\" data-id=\"635bcbe2\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;grid&quot;,&quot;grid_columns_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;3&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;grid_rows_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;content_width&quot;:&quot;boxed&quot;,&quot;grid_outline&quot;:&quot;yes&quot;,&quot;grid_columns_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_columns_grid_mobile&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;grid_rows_grid_tablet&quot;:{&quot;unit&quot;:&quot;fr&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_auto_flow&quot;:&quot;row&quot;,&quot;grid_auto_flow_tablet&quot;:&quot;row&quot;,&quot;grid_auto_flow_mobile&quot;:&quot;row&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3a8bb2ac e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"3a8bb2ac\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-751144cd e-con-full e-flex e-con e-child\" data-id=\"751144cd\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c207043 elementor-widget elementor-widget-image\" data-id=\"1c207043\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/11\/Group-50866.png\" class=\"attachment-full size-full wp-image-20046\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2593755f e-con-full e-flex e-con e-child\" data-id=\"2593755f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3456385e elementor-widget elementor-widget-heading\" data-id=\"3456385e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Ramakrishna Hegde<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4821f42f elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4821f42f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Principal<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Chairman<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52736924 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"52736924\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4246df4d e-con-full e-flex e-con e-child\" data-id=\"4246df4d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb9a34c elementor-widget elementor-widget-image\" data-id=\"3eb9a34c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ea98190 e-con-full e-flex e-con e-child\" data-id=\"1ea98190\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-230b455e elementor-widget elementor-widget-heading\" data-id=\"230b455e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prof. Melwin D&#8217;Souza<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39126107 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"39126107\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Vice Principal<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Convenor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5203c117 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"5203c117\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3830e789 e-con-full e-flex e-con e-child\" data-id=\"3830e789\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6527902e elementor-widget elementor-widget-image\" data-id=\"6527902e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6fa726c9 e-con-full e-flex e-con e-child\" data-id=\"6fa726c9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f6c73fd elementor-widget elementor-widget-heading\" data-id=\"5f6c73fd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Ramakrishna Hegde<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49c13b5d elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"49c13b5d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Dean-Student Welfare<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64b6f23c e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"64b6f23c\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6ae6a159 e-con-full e-flex e-con e-child\" data-id=\"6ae6a159\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2bcd11f2 elementor-widget elementor-widget-image\" data-id=\"2bcd11f2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63647cb0 e-con-full e-flex e-con e-child\" data-id=\"63647cb0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64749cd9 elementor-widget elementor-widget-heading\" data-id=\"64749cd9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Nikhila Pai<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46cccb5b elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"46cccb5b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65f3e624 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"65f3e624\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5f73db00 e-con-full e-flex e-con e-child\" data-id=\"5f73db00\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a34a88b elementor-widget elementor-widget-image\" data-id=\"2a34a88b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16977093 e-con-full e-flex e-con e-child\" data-id=\"16977093\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1181f4d0 elementor-widget elementor-widget-heading\" data-id=\"1181f4d0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prof. Deepak Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c020a9e elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6c020a9e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD(BSH)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c337dd e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"9c337dd\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-67e241bb e-con-full e-flex e-con e-child\" data-id=\"67e241bb\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78f0baf8 elementor-widget elementor-widget-image\" data-id=\"78f0baf8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-296382b2 e-con-full e-flex e-con e-child\" data-id=\"296382b2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c55d40d elementor-widget elementor-widget-heading\" data-id=\"1c55d40d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prof. Amruthamala<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-224daf9e elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"224daf9e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Dean(T&#038;P and IR)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50fe18ef e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"50fe18ef\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-13d2962f e-con-full e-flex e-con e-child\" data-id=\"13d2962f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6800e6 elementor-widget elementor-widget-image\" data-id=\"a6800e6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-107922c7 e-con-full e-flex e-con e-child\" data-id=\"107922c7\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-307d82fa elementor-widget elementor-widget-heading\" data-id=\"307d82fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prof. Asha Kumari<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72d4e025 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"72d4e025\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-350fd10d e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"350fd10d\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-293638e8 e-con-full e-flex e-con e-child\" data-id=\"293638e8\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79f2e6c0 elementor-widget elementor-widget-image\" data-id=\"79f2e6c0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26734078 e-con-full e-flex e-con e-child\" data-id=\"26734078\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-616205c2 elementor-widget elementor-widget-heading\" data-id=\"616205c2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prof. Muralidhara B K<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63a0b857 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"63a0b857\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD(CSE)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73552ca5 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"73552ca5\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-49ca3f6b e-con-full e-flex e-con e-child\" data-id=\"49ca3f6b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5df2876 elementor-widget elementor-widget-image\" data-id=\"5df2876\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23e0d546 e-con-full e-flex e-con e-child\" data-id=\"23e0d546\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65718be5 elementor-widget elementor-widget-heading\" data-id=\"65718be5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Basavaraj Kambale<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-408cd7b3 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"408cd7b3\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Associate Professor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Faculty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb59305 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"eb59305\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7ae01632 e-con-full e-flex e-con e-child\" data-id=\"7ae01632\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1536aec8 elementor-widget elementor-widget-image\" data-id=\"1536aec8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-27bf5e8e e-con-full e-flex e-con e-child\" data-id=\"27bf5e8e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c3fe272 elementor-widget elementor-widget-heading\" data-id=\"2c3fe272\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Mithun Shetty<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e2978ff elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6e2978ff\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-71244fd e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"71244fd\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-629e4799 e-con-full e-flex e-con e-child\" data-id=\"629e4799\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5943a338 elementor-widget elementor-widget-image\" data-id=\"5943a338\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fba6264 e-con-full e-flex e-con e-child\" data-id=\"1fba6264\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4e7aca elementor-widget elementor-widget-heading\" data-id=\"e4e7aca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Meghana<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e7f3d54 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7e7f3d54\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member-Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32fabe67 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"32fabe67\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-87cde59 e-con-full e-flex e-con e-child\" data-id=\"87cde59\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-755dc648 elementor-widget elementor-widget-image\" data-id=\"755dc648\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/11\/Group-50868.png\" class=\"attachment-full size-full wp-image-20048\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ad67f5e e-con-full e-flex e-con e-child\" data-id=\"3ad67f5e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73bc8063 elementor-widget elementor-widget-heading\" data-id=\"73bc8063\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Indra Vijay Singh<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0d2bfe elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e0d2bfe\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Dean R&#038;C and HOD-AI&#038;ML<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Co-ordinator<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7856a31b e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"7856a31b\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-45ce66b3 e-con-full e-flex e-con e-child\" data-id=\"45ce66b3\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2900ceb7 elementor-widget elementor-widget-image\" data-id=\"2900ceb7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/11\/Group-50869.png\" class=\"attachment-full size-full wp-image-20049\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75bd61b7 e-con-full e-flex e-con e-child\" data-id=\"75bd61b7\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50183733 elementor-widget elementor-widget-heading\" data-id=\"50183733\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Varuna Kumara<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f1d55a3 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3f1d55a3\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD-ECE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Co-Ordinator<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fadc775 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"7fadc775\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-50cd5ce5 e-con-full e-flex e-con e-child\" data-id=\"50cd5ce5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3716e728 elementor-widget elementor-widget-image\" data-id=\"3716e728\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/mr.manjunath.png\" class=\"attachment-full size-full wp-image-22699\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21117fb8 e-con-full e-flex e-con e-child\" data-id=\"21117fb8\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cea7e43 elementor-widget elementor-widget-heading\" data-id=\"6cea7e43\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Manjunath Lamani HoD CSE<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e813999 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3e813999\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD-CSE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d93508 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"6d93508\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1e003ee e-con-full e-flex e-con e-child\" data-id=\"1e003ee\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cedf137 elementor-widget elementor-widget-image\" data-id=\"cedf137\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50932.png\" class=\"attachment-full size-full wp-image-24008\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51950d0 e-con-full e-flex e-con e-child\" data-id=\"51950d0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88868e2 elementor-widget elementor-widget-heading\" data-id=\"88868e2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Sam Abraham<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b21888d elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b21888d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HoD CSEDS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c1da569 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"c1da569\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c98247b e-con-full e-flex e-con e-child\" data-id=\"c98247b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd74b1e elementor-widget elementor-widget-image\" data-id=\"fd74b1e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50932.png\" class=\"attachment-full size-full wp-image-24008\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7044f88 e-con-full e-flex e-con e-child\" data-id=\"7044f88\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-302cd97 elementor-widget elementor-widget-heading\" data-id=\"302cd97\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Sam Abraham<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b2caa3 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5b2caa3\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HoD CSEDS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b84f877 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"b84f877\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6af3b51 e-con-full e-flex e-con e-child\" data-id=\"6af3b51\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a69bcae elementor-widget elementor-widget-image\" data-id=\"a69bcae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-50845.png\" class=\"attachment-full size-full wp-image-20011\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-608d135 e-con-full e-flex e-con e-child\" data-id=\"608d135\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40bdeb0 elementor-widget elementor-widget-heading\" data-id=\"40bdeb0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Suchitra Poojari<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab32991 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ab32991\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HoD MBA <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39e73fec e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"39e73fec\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-73d41337 e-con-full e-flex e-con e-child\" data-id=\"73d41337\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88aa094 elementor-widget elementor-widget-image\" data-id=\"88aa094\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/11\/Group-50871.png\" class=\"attachment-full size-full wp-image-20051\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-131192e0 e-con-full e-flex e-con e-child\" data-id=\"131192e0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34cd6458 elementor-widget elementor-widget-heading\" data-id=\"34cd6458\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. T. Nandhini<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ece3d33 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1ece3d33\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HOD-MCA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2caedbb6 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"2caedbb6\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3816ad4e e-con-full e-flex e-con e-child\" data-id=\"3816ad4e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6364e16e elementor-widget elementor-widget-image\" data-id=\"6364e16e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/11\/Group-50874.png\" class=\"attachment-full size-full wp-image-20054\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54a60dd7 e-con-full e-flex e-con e-child\" data-id=\"54a60dd7\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5dc8a00b elementor-widget elementor-widget-heading\" data-id=\"5dc8a00b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Shrinidhi N\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7115648d elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7115648d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HoD Incharge AI&#038;ML<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b29139 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"3b29139\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b162049 e-con-full e-flex e-con e-child\" data-id=\"b162049\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e28398d elementor-widget elementor-widget-image\" data-id=\"e28398d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/11\/Group-1000006297.png\" class=\"attachment-full size-full wp-image-25729\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd23953 e-con-full e-flex e-con e-child\" data-id=\"cd23953\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a242411 elementor-widget elementor-widget-heading\" data-id=\"a242411\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Lakshmi\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b183ffb elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b183ffb\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: HoD Incharge ISE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72183373 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"72183373\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-22f973cf e-con-full e-flex e-con e-child\" data-id=\"22f973cf\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22eeffa0 elementor-widget elementor-widget-image\" data-id=\"22eeffa0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/11\/Group-50872.png\" class=\"attachment-full size-full wp-image-20052\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb81d9 e-con-full e-flex e-con e-child\" data-id=\"bb81d9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36f05376 elementor-widget elementor-widget-heading\" data-id=\"36f05376\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Chaithra<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42909f12 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"42909f12\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Assistant Prof., BSH<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-752395a6 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"752395a6\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1502e33f e-con-full e-flex e-con e-child\" data-id=\"1502e33f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34fbb980 elementor-widget elementor-widget-image\" data-id=\"34fbb980\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/11\/Group-50873.png\" class=\"attachment-full size-full wp-image-20053\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10d486dc e-con-full e-flex e-con e-child\" data-id=\"10d486dc\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13c9af39 elementor-widget elementor-widget-heading\" data-id=\"13c9af39\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Smithashree\n\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-670c0eba elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"670c0eba\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty-CSE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e445d43 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"7e445d43\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3a42308 e-con-full e-flex e-con e-child\" data-id=\"3a42308\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-543cba52 elementor-widget elementor-widget-image\" data-id=\"543cba52\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/11\/Group-50875.png\" class=\"attachment-full size-full wp-image-20055\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-449e67df e-con-full e-flex e-con e-child\" data-id=\"449e67df\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d21e8a elementor-widget elementor-widget-heading\" data-id=\"3d21e8a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mrs. Nagaveni\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24859fbe elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"24859fbe\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Faculty- MBA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b8dd1ca e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"6b8dd1ca\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-30264792 e-con-full e-flex e-con e-child\" data-id=\"30264792\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2bcc0ed1 elementor-widget elementor-widget-image\" data-id=\"2bcc0ed1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c917aaa e-con-full e-flex e-con e-child\" data-id=\"1c917aaa\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9833c5b elementor-widget elementor-widget-heading\" data-id=\"9833c5b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Sudheer Shetty\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68200a63 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"68200a63\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: PRO<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2fe77404 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"2fe77404\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3ebc9d78 e-con-full e-flex e-con e-child\" data-id=\"3ebc9d78\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-785c54ec elementor-widget elementor-widget-image\" data-id=\"785c54ec\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f3bec34 e-con-full e-flex e-con e-child\" data-id=\"4f3bec34\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58eed385 elementor-widget elementor-widget-heading\" data-id=\"58eed385\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. G N Sandhya (4MK25BA029)\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bea3c7d elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2bea3c7d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c2e54aa e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"c2e54aa\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b5e5142 e-con-full e-flex e-con e-child\" data-id=\"b5e5142\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dce6ab elementor-widget elementor-widget-image\" data-id=\"2dce6ab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a7d7fa e-con-full e-flex e-con e-child\" data-id=\"4a7d7fa\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee977d1 elementor-widget elementor-widget-heading\" data-id=\"ee977d1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ms. Sanmitha (4MK25MC038)\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-776ed7a elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"776ed7a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-030ee06 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"030ee06\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6e0a59d e-con-full e-flex e-con e-child\" data-id=\"6e0a59d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3846b2a elementor-widget elementor-widget-image\" data-id=\"3846b2a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06b350a e-con-full e-flex e-con e-child\" data-id=\"06b350a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32f0a61 elementor-widget elementor-widget-heading\" data-id=\"32f0a61\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Rithesh (4MK24EC402)\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-417256e elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"417256e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76015670 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"76015670\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-68890488 e-con-full e-flex e-con e-child\" data-id=\"68890488\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c1a94ac elementor-widget elementor-widget-image\" data-id=\"6c1a94ac\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75581fd8 e-con-full e-flex e-con e-child\" data-id=\"75581fd8\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15ba46a1 elementor-widget elementor-widget-heading\" data-id=\"15ba46a1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Indraj A Gouda (4MK23CS041)\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2beea859 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2beea859\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c24f82a e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"3c24f82a\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6a671465 e-con-full e-flex e-con e-child\" data-id=\"6a671465\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fa3d7c elementor-widget elementor-widget-image\" data-id=\"7fa3d7c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"96\" src=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855-2.png\" class=\"attachment-full size-full wp-image-6361\" alt=\"FACULTY\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61637f17 e-con-full e-flex e-con e-child\" data-id=\"61637f17\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d315136 elementor-widget elementor-widget-heading\" data-id=\"6d315136\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mr. Nandan Shetty (4MK23CS065)\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-291c6e71 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"291c6e71\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"15\" viewBox=\"0 0 17 15\" fill=\"none\"><path d=\"M15.3001 2.75082H11.7545V1.83545C11.7542 1.50287 11.6219 1.18402 11.3867 0.948853C11.1516 0.713685 10.8327 0.581411 10.5001 0.581055H6.57864C6.24604 0.581411 5.92717 0.71368 5.69198 0.948842C5.45678 1.18401 5.32447 1.50286 5.32407 1.83545V2.75082H1.81048C1.51504 2.75113 1.23179 2.86862 1.02286 3.07751C0.813936 3.28641 0.696402 3.56964 0.696046 3.86509V7.20756C0.695908 7.2733 0.717768 7.33721 0.758146 7.38909C0.798525 7.44098 0.8551 7.47786 0.918866 7.49387L1.2515 7.57808V13.3071C1.25181 13.602 1.36911 13.8848 1.57766 14.0933C1.78621 14.3019 2.06898 14.4192 2.36391 14.4195H14.7467C15.0416 14.4192 15.3244 14.3019 15.533 14.0933C15.7416 13.8848 15.8589 13.602 15.8593 13.3071V7.57724L16.1917 7.49303C16.2555 7.47702 16.3121 7.44013 16.3525 7.38825C16.3928 7.33636 16.4147 7.27246 16.4146 7.20672V3.86576C16.4144 3.5702 16.2969 3.28679 16.088 3.07775C15.879 2.86871 15.5957 2.75113 15.3001 2.75082ZM5.91354 1.83545C5.91377 1.65914 5.98392 1.49012 6.1086 1.36546C6.23329 1.24081 6.40233 1.1707 6.57864 1.17053H10.5001C10.6764 1.1707 10.8455 1.24082 10.9701 1.36548C11.0948 1.49013 11.1649 1.65916 11.1651 1.83545V2.75082H5.91354V1.83545ZM1.28552 3.86576C1.28552 3.72648 1.34081 3.5929 1.43925 3.49437C1.53768 3.39584 1.67121 3.34042 1.81048 3.34029H15.301C15.4401 3.34042 15.5735 3.39575 15.672 3.49413C15.7704 3.59252 15.8258 3.72593 15.8259 3.86509V6.97817L15.497 7.06154H15.493L9.57955 8.56014V8.36242C9.57937 8.17478 9.50482 7.99485 9.37223 7.86207C9.23965 7.72929 9.05983 7.65449 8.87219 7.65404H8.20676C8.01894 7.65422 7.83886 7.72891 7.70606 7.86172C7.57325 7.99453 7.49856 8.1746 7.49838 8.36242V8.55054L1.61815 7.06238L1.28552 6.97817V3.86576ZM8.08785 8.92915V8.36242C8.0879 8.3309 8.10044 8.30068 8.12273 8.27839C8.14502 8.2561 8.17524 8.24356 8.20676 8.24351H8.87219C8.90371 8.24356 8.93393 8.2561 8.95622 8.27839C8.97851 8.30068 8.99105 8.3309 8.99109 8.36242V9.82549C8.99105 9.85701 8.97851 9.88723 8.95622 9.90952C8.93393 9.93181 8.90371 9.94435 8.87219 9.94439H8.20676C8.17524 9.94435 8.14502 9.93181 8.12273 9.90952C8.10044 9.88723 8.0879 9.85701 8.08785 9.82549V8.92915ZM14.7467 13.8302H2.36391C2.22527 13.83 2.09236 13.7749 1.99433 13.6768C1.8963 13.5788 1.84115 13.4459 1.84097 13.3072V7.7268L7.29055 9.10599L7.49838 9.15871V9.82549C7.49834 9.84546 7.50037 9.86539 7.50444 9.88494C7.51907 10.0614 7.59932 10.2259 7.72935 10.346C7.85937 10.4662 8.02972 10.5332 8.20676 10.5339H8.87219C9.04922 10.5332 9.21957 10.4662 9.3496 10.346C9.47962 10.2259 9.55987 10.0614 9.5745 9.88494C9.57824 9.86535 9.57993 9.84543 9.57955 9.82549V9.16764L14.839 7.83476L15.2696 7.72562V13.3071C15.2695 13.4457 15.2143 13.5786 15.1163 13.6767C15.0182 13.7747 14.8853 13.83 14.7467 13.8302Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profession: Student<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><path d=\"M12.2429 2.5H9.43042V1.875C9.43042 0.84125 8.58917 0 7.55542 0C6.52167 0 5.68042 0.84125 5.68042 1.875V2.5H2.86792C2.12225 2.50083 1.40736 2.79741 0.880096 3.32468C0.352829 3.85194 0.0562471 4.56683 0.0554199 5.3125L0.0554199 12.1875C0.0554199 13.7381 1.31729 15 2.86792 15H12.2429C13.7935 15 15.0554 13.7381 15.0554 12.1875V5.3125C15.0554 3.76188 13.7935 2.5 12.2429 2.5ZM6.30542 1.875C6.30542 1.18562 6.86604 0.625 7.55542 0.625C8.24479 0.625 8.80542 1.18562 8.80542 1.875V3.75C8.80542 3.91576 8.73957 4.07473 8.62236 4.19194C8.50515 4.30915 8.34618 4.375 8.18042 4.375H6.93042C6.76466 4.375 6.60569 4.30915 6.48848 4.19194C6.37127 4.07473 6.30542 3.91576 6.30542 3.75V1.875ZM14.4304 12.1875C14.4304 13.3938 13.4492 14.375 12.2429 14.375H2.86792C1.66167 14.375 0.68042 13.3938 0.68042 12.1875V5.3125C0.68042 4.10625 1.66167 3.125 2.86792 3.125H5.68042V3.75C5.68042 4.43937 6.24104 5 6.93042 5H8.18042C8.86979 5 9.43042 4.43937 9.43042 3.75V3.125H12.2429C13.4492 3.125 14.4304 4.10625 14.4304 5.3125V12.1875ZM5.68042 6.875H3.80542C3.11604 6.875 2.55542 7.43563 2.55542 8.125V11.25C2.55542 11.9394 3.11604 12.5 3.80542 12.5H5.68042C6.36979 12.5 6.93042 11.9394 6.93042 11.25V8.125C6.93042 7.43563 6.36979 6.875 5.68042 6.875ZM6.30542 11.25C6.30542 11.4158 6.23957 11.5747 6.12236 11.6919C6.00515 11.8092 5.84618 11.875 5.68042 11.875H3.80542C3.63966 11.875 3.48069 11.8092 3.36348 11.6919C3.24627 11.5747 3.18042 11.4158 3.18042 11.25V8.125C3.18042 7.95924 3.24627 7.80027 3.36348 7.68306C3.48069 7.56585 3.63966 7.5 3.80542 7.5H5.68042C5.84618 7.5 6.00515 7.56585 6.12236 7.68306C6.23957 7.80027 6.30542 7.95924 6.30542 8.125V11.25ZM12.5554 9.6875C12.5554 9.77038 12.5225 9.84987 12.4639 9.90847C12.4053 9.96708 12.3258 10 12.2429 10H8.49292C8.41004 10 8.33055 9.96708 8.27195 9.90847C8.21334 9.84987 8.18042 9.77038 8.18042 9.6875C8.18042 9.60462 8.21334 9.52513 8.27195 9.46653C8.33055 9.40792 8.41004 9.375 8.49292 9.375H12.2429C12.3258 9.375 12.4053 9.40792 12.4639 9.46653C12.5225 9.52513 12.5554 9.60462 12.5554 9.6875ZM12.5554 7.1875C12.5554 7.27038 12.5225 7.34987 12.4639 7.40847C12.4053 7.46708 12.3258 7.5 12.2429 7.5H8.49292C8.41004 7.5 8.33055 7.46708 8.27195 7.40847C8.21334 7.34987 8.18042 7.27038 8.18042 7.1875C8.18042 7.10462 8.21334 7.02513 8.27195 6.96653C8.33055 6.90792 8.41004 6.875 8.49292 6.875H12.2429C12.3258 6.875 12.4053 6.90792 12.4639 6.96653C12.5225 7.02513 12.5554 7.10462 12.5554 7.1875ZM11.3054 12.1875C11.3054 12.2704 11.2725 12.3499 11.2139 12.4085C11.1553 12.4671 11.0758 12.5 10.9929 12.5H8.49292C8.41004 12.5 8.33055 12.4671 8.27195 12.4085C8.21334 12.3499 8.18042 12.2704 8.18042 12.1875C8.18042 12.1046 8.21334 12.0251 8.27195 11.9665C8.33055 11.9079 8.41004 11.875 8.49292 11.875H10.9929C11.0758 11.875 11.1553 11.9079 11.2139 11.9665C11.2725 12.0251 11.3054 12.1046 11.3054 12.1875Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designation : Member<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7739230 e-flex e-con-boxed e-con e-parent\" data-id=\"7739230\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aee3a53 elementor-widget elementor-widget-html\" data-id=\"aee3a53\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<script>\n    function handleHashChange() {\n    const hash = window.location.hash;\n    \n\n    if (hash.includes('#committees')) {\n        \/\/ Extract section identifier from the hash\n        const section = hash.split('-')[1]; \/\/ Example: #committees-icc -> icc\n\n        \/\/ Activate the \"committees\" tab\n        const committeesTab = document.querySelector('[data-ekit-handler-id=\"committees\"]');\n        if (committeesTab) {\n            committeesTab.click(); \/\/ Activate the tab\n        }\n\n        \/\/ Scroll to the target section after ensuring tab content is visible\n        const targetSection = document.getElementById(section);\n        if (targetSection) {\n            \/\/ setTimeout(() => {\n            \/\/     targetSection.scrollIntoView({ behavior: 'smooth' });\n            \/\/ }, 500); \/\/ Adjust delay if necessary\n                setTimeout(() => {\n                    \/\/ Get the position of the target section\n                    const targetPosition = targetSection.getBoundingClientRect().top + window.pageYOffset;\n\n                    \/\/ Get the height of the sticky header\n                    const headerHeight = document.querySelector('header').offsetHeight;\n\n                    \/\/ Scroll to the target section with offset for the sticky header\n                    window.scrollTo({\n                        top: targetPosition - headerHeight-50,\n                        behavior: 'smooth'\n                    });\n                }, 500); \/\/ Adjust delay if necessary\n        }\n    }\n};\n\n\/\/ Run the function on page load\ndocument.addEventListener('DOMContentLoaded', handleHashChange);\n\n\/\/ Also run the function whenever the hash changes\nwindow.addEventListener('hashchange', handleHashChange);\n\n<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>                        <\/div>\n                    <\/div>\n                                \n            <\/div>\n                    <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Councils &#038; Committees Supporting student growth and campus governance through active councils, committees, and leadership initiatives. Governing Council Academic Council Committees Sri. Siddartha J Shetty Profession : Educationist Designation : Trustee, Chairman Dr. Ramakrishna Hegde Profession : Principal\/Member Secretary Designation : Member Secretary Dr. S N Bhat Profession : Director Academics IMJ Institutions Designation :&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"class_list":["post-6327","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Councils &amp; Committees | Governance at MIT Kundapura<\/title>\n<meta name=\"description\" content=\"Discover the Councils &amp; Committees at MIT Kundapura. Ensuring academic excellence, student welfare, and institutional development.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Councils &amp; Committees | Governance at MIT Kundapura\" \/>\n<meta property=\"og:description\" content=\"Discover the Councils &amp; Committees at MIT Kundapura. Ensuring academic excellence, student welfare, and institutional development.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/\" \/>\n<meta property=\"og:site_name\" content=\"MIT Kundapura\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-06T07:27:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/02\/MIT-Kundapura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Councils &amp; Committees | Governance at MIT Kundapura\" \/>\n<meta name=\"twitter:description\" content=\"Discover the Councils &amp; Committees at MIT Kundapura. Ensuring academic excellence, student welfare, and institutional development.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/02\/MIT-Kundapura.png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mitkundapura.com\\\/index.php\\\/councils-committees\\\/\",\"url\":\"https:\\\/\\\/www.mitkundapura.com\\\/index.php\\\/councils-committees\\\/\",\"name\":\"Councils & Committees | Governance at MIT Kundapura\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mitkundapura.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mitkundapura.com\\\/index.php\\\/councils-committees\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mitkundapura.com\\\/index.php\\\/councils-committees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mitkundapura.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Group-49855.png\",\"datePublished\":\"2024-03-22T05:39:29+00:00\",\"dateModified\":\"2026-04-06T07:27:47+00:00\",\"description\":\"Discover the Councils & Committees at MIT Kundapura. Ensuring academic excellence, student welfare, and institutional development.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mitkundapura.com\\\/index.php\\\/councils-committees\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mitkundapura.com\\\/index.php\\\/councils-committees\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.mitkundapura.com\\\/index.php\\\/councils-committees\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mitkundapura.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Group-49855.png\",\"contentUrl\":\"https:\\\/\\\/www.mitkundapura.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Group-49855.png\",\"width\":91,\"height\":96,\"caption\":\"FACULTY\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mitkundapura.com\\\/index.php\\\/councils-committees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mitkundapura.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Councils &amp; Committees\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mitkundapura.com\\\/#website\",\"url\":\"https:\\\/\\\/www.mitkundapura.com\\\/\",\"name\":\"MIT Kundapura\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mitkundapura.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Councils & Committees | Governance at MIT Kundapura","description":"Discover the Councils & Committees at MIT Kundapura. Ensuring academic excellence, student welfare, and institutional development.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/","og_locale":"en_US","og_type":"article","og_title":"Councils & Committees | Governance at MIT Kundapura","og_description":"Discover the Councils & Committees at MIT Kundapura. Ensuring academic excellence, student welfare, and institutional development.","og_url":"https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/","og_site_name":"MIT Kundapura","article_modified_time":"2026-04-06T07:27:47+00:00","og_image":[{"width":1081,"height":1080,"url":"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/02\/MIT-Kundapura.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Councils & Committees | Governance at MIT Kundapura","twitter_description":"Discover the Councils & Committees at MIT Kundapura. Ensuring academic excellence, student welfare, and institutional development.","twitter_image":"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2025\/02\/MIT-Kundapura.png","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/","url":"https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/","name":"Councils & Committees | Governance at MIT Kundapura","isPartOf":{"@id":"https:\/\/www.mitkundapura.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/#primaryimage"},"image":{"@id":"https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855.png","datePublished":"2024-03-22T05:39:29+00:00","dateModified":"2026-04-06T07:27:47+00:00","description":"Discover the Councils & Committees at MIT Kundapura. Ensuring academic excellence, student welfare, and institutional development.","breadcrumb":{"@id":"https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/#primaryimage","url":"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855.png","contentUrl":"https:\/\/www.mitkundapura.com\/wp-content\/uploads\/2024\/03\/Group-49855.png","width":91,"height":96,"caption":"FACULTY"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mitkundapura.com\/index.php\/councils-committees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mitkundapura.com\/"},{"@type":"ListItem","position":2,"name":"Councils &amp; Committees"}]},{"@type":"WebSite","@id":"https:\/\/www.mitkundapura.com\/#website","url":"https:\/\/www.mitkundapura.com\/","name":"MIT Kundapura","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mitkundapura.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.mitkundapura.com\/index.php\/wp-json\/wp\/v2\/pages\/6327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mitkundapura.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mitkundapura.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mitkundapura.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mitkundapura.com\/index.php\/wp-json\/wp\/v2\/comments?post=6327"}],"version-history":[{"count":1,"href":"https:\/\/www.mitkundapura.com\/index.php\/wp-json\/wp\/v2\/pages\/6327\/revisions"}],"predecessor-version":[{"id":25818,"href":"https:\/\/www.mitkundapura.com\/index.php\/wp-json\/wp\/v2\/pages\/6327\/revisions\/25818"}],"wp:attachment":[{"href":"https:\/\/www.mitkundapura.com\/index.php\/wp-json\/wp\/v2\/media?parent=6327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}